{"id":14480,"date":"2021-01-07T15:34:10","date_gmt":"2021-01-07T14:34:10","guid":{"rendered":"https:\/\/james-mac.com\/?p=14480"},"modified":"2021-01-07T15:47:42","modified_gmt":"2021-01-07T14:47:42","slug":"erst-aquarium-dann-50-kalamare","status":"publish","type":"post","link":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/","title":{"rendered":"Erst Aquarium, dann 50 Kalamare"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14480\" class=\"elementor elementor-14480\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6dadd193 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dadd193\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb222c9\" data-id=\"bb222c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-77684c00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77684c00\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-19cf3e9e\" data-id=\"19cf3e9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-element elementor-element-4a4beba2 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"4a4beba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/beim-hotspot-fuer-seepferdchen\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Voriger<\/span><span class=\"post-navigation__prev--title\">Beim Hotspot f\u00fcr Seepferdchen<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/gleich-morgens-direkt-richtung-norden\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster<\/span><span class=\"post-navigation__next--title\">Gleich morgens direkt Richtung Norden<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2afd2b9e elementor-widget elementor-widget-shortcode\" data-id=\"2afd2b9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e69217 elementor-widget elementor-widget-shortcode\" data-id=\"40e69217\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78fa2494 elementor-widget elementor-widget-text-editor\" data-id=\"78fa2494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c4gypten, Rotes Meer, Hurghada, Deutsche Tauchschule, James &amp; Mac Diving Center &#8211; Fotonachweise: salze-productions, James &amp; Mac<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6fffe481 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fffe481\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4446cff\" data-id=\"4446cff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5fb009d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fb009d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-61b46dc1\" data-id=\"61b46dc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54e2eed5 elementor-widget elementor-widget-wp-widget-archives\" data-id=\"54e2eed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-archives.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5>Archiv<\/h5>\t\t<label class=\"screen-reader-text\" for=\"archives-dropdown-REPLACE_TO_ID\">Archiv<\/label>\n\t\t<select id=\"archives-dropdown-REPLACE_TO_ID\" name=\"archive-dropdown\">\n\t\t\t\n\t\t\t<option value=\"\">Select Month<\/option>\n\t\t\t\t<option value='https:\/\/james-mac.com\/en\/2026\/07\/'> July 2026 &nbsp;(16)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/06\/'> June 2026 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/05\/'> May 2026 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/04\/'> April 2026 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/03\/'> March 2026 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/02\/'> February 2026 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/01\/'> January 2026 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/12\/'> December 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/11\/'> November 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/10\/'> October 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/09\/'> September 2025 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/08\/'> August 2025 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/07\/'> July 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/06\/'> June 2025 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/05\/'> May 2025 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/04\/'> April 2025 &nbsp;(30)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/03\/'> March 2025 &nbsp;(31)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/02\/'> February 2025 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/01\/'> January 2025 &nbsp;(31)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/12\/'> December 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/11\/'> November 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/10\/'> October 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/09\/'> September 2024 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/08\/'> August 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/07\/'> July 2024 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/06\/'> June 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/05\/'> May 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/04\/'> April 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/03\/'> March 2024 &nbsp;(37)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/02\/'> February 2024 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/01\/'> January 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/12\/'> December 2023 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/11\/'> November 2023 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/10\/'> October 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/09\/'> September 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/08\/'> August 2023 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/07\/'> July 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/06\/'> June 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/05\/'> May 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/04\/'> April 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/03\/'> March 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/02\/'> February 2023 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/01\/'> January 2023 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/12\/'> December 2022 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/11\/'> November 2022 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/10\/'> October 2022 &nbsp;(41)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/09\/'> September 2022 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/08\/'> August 2022 &nbsp;(26)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/07\/'> July 2022 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/06\/'> June 2022 &nbsp;(24)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/05\/'> May 2022 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/04\/'> April 2022 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/03\/'> March 2022 &nbsp;(21)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/02\/'> February 2022 &nbsp;(27)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/01\/'> January 2022 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/12\/'> December 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/11\/'> November 2021 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/10\/'> October 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/09\/'> September 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/08\/'> August 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/07\/'> July 2021 &nbsp;(42)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/06\/'> June 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/05\/'> May 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/04\/'> April 2021 &nbsp;(45)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/03\/'> March 2021 &nbsp;(46)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/02\/'> February 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/01\/'> January 2021 &nbsp;(46)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/12\/'> December 2020 &nbsp;(50)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/11\/'> November 2020 &nbsp;(43)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/10\/'> October 2020 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/09\/'> September 2020 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/08\/'> August 2020 &nbsp;(24)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/07\/'> July 2020 &nbsp;(22)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/06\/'> June 2020 &nbsp;(19)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/01\/'> January 2020 &nbsp;(1)<\/option>\n\n\t\t<\/select>\n\n\t\t\t<script>\n( ( dropdownId ) => {\n\tconst dropdown = document.getElementById( dropdownId );\n\tfunction onSelectChange() {\n\t\tsetTimeout( () => {\n\t\t\tif ( 'escape' === dropdown.dataset.lastkey ) {\n\t\t\t\treturn;\n\t\t\t}\n\t\t\tif ( dropdown.value ) {\n\t\t\t\tdocument.location.href = dropdown.value;\n\t\t\t}\n\t\t}, 250 );\n\t}\n\tfunction onKeyUp( event ) {\n\t\tif ( 'Escape' === event.key ) {\n\t\t\tdropdown.dataset.lastkey = 'escape';\n\t\t} else {\n\t\t\tdelete dropdown.dataset.lastkey;\n\t\t}\n\t}\n\tfunction onClick() {\n\t\tdelete dropdown.dataset.lastkey;\n\t}\n\tdropdown.addEventListener( 'keyup', onKeyUp );\n\tdropdown.addEventListener( 'click', onClick );\n\tdropdown.addEventListener( 'change', onSelectChange );\n})( \"archives-dropdown-REPLACE_TO_ID\" );\n\n\/\/# sourceURL=WP_Widget_Archives%3A%3Awidget\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c4gypten, Rotes Meer, Hurghada, Deutsche Tauchschule, James &amp; Mac Diving Center &#8211; Fotonachweise: salze-productions, James &amp; Mac<\/p>","protected":false},"author":4,"featured_media":14486,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[256,369,321],"class_list":["post-14480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-taegliche-tauchausfahrten","tag-aquarium","tag-shaab-abu-ramada","tag-shaab-eshta","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center<\/title>\n<meta name=\"description\" content=\"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center\" \/>\n<meta property=\"og:description\" content=\"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/\" \/>\n<meta property=\"og:site_name\" content=\"James &amp; Mac Diving Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jamesandmac\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-07T14:34:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-07T14:47:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2166\" \/>\n\t<meta property=\"og:image:height\" content=\"1624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ameli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:site\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ameli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/\"},\"author\":{\"name\":\"Ameli\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\"},\"headline\":\"Erst Aquarium, dann 50 Kalamare\",\"datePublished\":\"2021-01-07T14:34:10+00:00\",\"dateModified\":\"2021-01-07T14:47:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/\"},\"wordCount\":27,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kalamar-Salzeproductions-4x3-1.jpg\",\"keywords\":[\"Aquarium\",\"Shaab Abu Ramada\",\"Shaab Eshta\"],\"articleSection\":[\"T\u00e4gliche Tauchausfahrten\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/\",\"name\":\"Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kalamar-Salzeproductions-4x3-1.jpg\",\"datePublished\":\"2021-01-07T14:34:10+00:00\",\"dateModified\":\"2021-01-07T14:47:42+00:00\",\"description\":\"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kalamar-Salzeproductions-4x3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kalamar-Salzeproductions-4x3-1.jpg\",\"width\":2166,\"height\":1624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/erst-aquarium-dann-50-kalamare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/james-mac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e4gliche Tauchausfahrten\",\"item\":\"https:\\\/\\\/james-mac.com\\\/category\\\/taegliche-tauchausfahrten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Erst Aquarium, dann 50 Kalamare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"name\":\"James &amp; Mac Diving Center\",\"description\":\"Red sea diving since 1987\",\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/james-mac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\",\"name\":\"James & Mac\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"James & Mac\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jamesandmac\\\/\",\"https:\\\/\\\/x.com\\\/James_Mac_HRG\",\"https:\\\/\\\/www.instagram.com\\\/jamesundmacdiving\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/james1987mac\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\",\"name\":\"Ameli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"caption\":\"Ameli\"},\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/author\\\/ameli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center","description":"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/","og_locale":"en_GB","og_type":"article","og_title":"Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center","og_description":"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.","og_url":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/","og_site_name":"James &amp; Mac Diving Center","article_publisher":"https:\/\/www.facebook.com\/jamesandmac\/","article_published_time":"2021-01-07T14:34:10+00:00","article_modified_time":"2021-01-07T14:47:42+00:00","og_image":[{"width":2166,"height":1624,"url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg","type":"image\/jpeg"}],"author":"Ameli","twitter_card":"summary_large_image","twitter_creator":"@James_Mac_HRG","twitter_site":"@James_Mac_HRG","twitter_misc":{"Written by":"Ameli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#article","isPartOf":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/"},"author":{"name":"Ameli","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4"},"headline":"Erst Aquarium, dann 50 Kalamare","datePublished":"2021-01-07T14:34:10+00:00","dateModified":"2021-01-07T14:47:42+00:00","mainEntityOfPage":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/"},"wordCount":27,"commentCount":0,"publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"image":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg","keywords":["Aquarium","Shaab Abu Ramada","Shaab Eshta"],"articleSection":["T\u00e4gliche Tauchausfahrten"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/","url":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/","name":"Erst Aquarium, dann 50 Kalamare - James &amp; Mac Diving Center","isPartOf":{"@id":"https:\/\/james-mac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#primaryimage"},"image":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg","datePublished":"2021-01-07T14:34:10+00:00","dateModified":"2021-01-07T14:47:42+00:00","description":"Erst Aquarium, dann 50 Kalamare. So l\u00e4sst sich der Tauchtag heute in Kurzfassung beschreiben. Bei Shaab Eshta waren unglaublich viele Fische.","breadcrumb":{"@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#primaryimage","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Kalamar-Salzeproductions-4x3-1.jpg","width":2166,"height":1624},{"@type":"BreadcrumbList","@id":"https:\/\/james-mac.com\/en\/erst-aquarium-dann-50-kalamare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/james-mac.com\/"},{"@type":"ListItem","position":2,"name":"T\u00e4gliche Tauchausfahrten","item":"https:\/\/james-mac.com\/category\/taegliche-tauchausfahrten\/"},{"@type":"ListItem","position":3,"name":"Erst Aquarium, dann 50 Kalamare"}]},{"@type":"WebSite","@id":"https:\/\/james-mac.com\/#website","url":"https:\/\/james-mac.com\/","name":"James &amp; Mac Diving Center","description":"Red sea diving since 1987","publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/james-mac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/james-mac.com\/#organization","name":"James &amp; Mac","url":"https:\/\/james-mac.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"James & Mac"},"image":{"@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jamesandmac\/","https:\/\/x.com\/James_Mac_HRG","https:\/\/www.instagram.com\/jamesundmacdiving\/","https:\/\/www.youtube.com\/user\/james1987mac"]},{"@type":"Person","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4","name":"Ameli","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","caption":"Ameli"},"url":"https:\/\/james-mac.com\/en\/author\/ameli\/"}]}},"_links":{"self":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/14480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/comments?post=14480"}],"version-history":[{"count":8,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/14480\/revisions"}],"predecessor-version":[{"id":14490,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/14480\/revisions\/14490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media\/14486"}],"wp:attachment":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media?parent=14480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/categories?post=14480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/tags?post=14480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}