{"id":18205,"date":"2021-04-13T08:00:00","date_gmt":"2021-04-13T06:00:00","guid":{"rendered":"https:\/\/james-mac.com\/?p=18205"},"modified":"2021-04-14T10:21:55","modified_gmt":"2021-04-14T08:21:55","slug":"red-sea-partner-raetsel-spanische-taenzerin","status":"publish","type":"post","link":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/","title":{"rendered":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18205\" class=\"elementor elementor-18205\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-51e2850 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51e2850\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64068826\" data-id=\"64068826\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-359eb9f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"359eb9f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5aced5be\" data-id=\"5aced5be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-element elementor-element-696d0546 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"696d0546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/morgen-beginnt-der-fastenmonat-ramadan\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Voriger<\/span><span class=\"post-navigation__prev--title\">Morgen beginnt der Fastenmonat Ramadan<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/faszinierend-und-selten-mondfisch-sichtung\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster<\/span><span class=\"post-navigation__next--title\">Faszinierend und selten: Mondfisch Sichtung<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66b5ebe2 elementor-widget elementor-widget-shortcode\" data-id=\"66b5ebe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6285b05c elementor-widget elementor-widget-spacer\" data-id=\"6285b05c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592fd78 elementor-widget elementor-widget-heading\" data-id=\"592fd78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Das Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5687fc elementor-widget elementor-widget-text-editor\" data-id=\"3d5687fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Diese Unterwasser Sch\u00f6nheit ist eine Spanische T\u00e4nzerin. Sie geh\u00f6rt zu den Nacktschnecken und macht ihrem Namen alle Ehre wenn sie unterwegs ist. Diese Nacktschnecke besitzt eine erstaunliche F\u00e4higkeit sich mit\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=Rwgz27RZvv4\" target=\"_blank\" rel=\"noopener\">wellenf\u00f6rmigen Bewegungen<\/a> ihres Mantels im Wasser fortzubewegen, welches ihr den Popul\u00e4rnamen \u201eSpanische T\u00e4nzerin\u201c verliehen hat. Sie ist meist nachtaktiv und im Schein der Taucherlampe vollf\u00fchrt sie\u00a0einen anmutigen Tanz.<\/p><p class=\"p1\">Kommen wir nun aber zu unserem R\u00e4tsel:<\/p><p class=\"p1\">F\u00fcr das folgende R\u00e4tsel seht ihr 2 Bilder, links das Original, rechts das gleiche Bild mit Netz. Das Bild rechts wurde gespiegelt und mit mehreren Fehlern versehen. 6 Fehler m\u00fcsst ihr finden und alphabetisch und numerisch sortieren.<\/p><p class=\"p1\">Beispiel: A2, C6, E1, E2, G6, I3<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e3c3a6a elementor-widget elementor-widget-spacer\" data-id=\"6e3c3a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77803779 elementor-widget elementor-widget-image\" data-id=\"77803779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-1024x682.png\" class=\"attachment-large size-large wp-image-15490\" alt=\"Unterwasser\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-1024x682.png 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-300x200.png 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-768x511.png 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-1536x1023.png 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-16x12.png 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-174x116.png 174w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin.png 1984w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba2f578 elementor-widget elementor-widget-spacer\" data-id=\"2ba2f578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73e7db62 elementor-widget elementor-widget-text-editor\" data-id=\"73e7db62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><b>Was gibt es zu gewinnen?<\/b><\/p><p class=\"p1\">Der Gewinn ist ein Feld auf unserem Red Sea PARTner Kunstwerk im Wert von 85,- Euro.<\/p><p class=\"p1\"><a href=\"https:\/\/james-mac.com\/der-ganze-rest\/sei-ein-red-sea-partner\/\" target=\"_blank\" rel=\"noopener\">Red Sea PARTner<\/a> ist eine Initiative unserer beiden Tauchbasen in Hurghada: James &amp; Mac Diving Center sowie Blue Water Dive Resort. Ziel ist es, dass alle, die das Rote Meer lieben, ein Teil dieser Initiative und somit ein Red Sea PARTner werden. Diese verr\u00fcckte Idee basiert auf der Gestaltung einer gro\u00dfen Landkarte der Region \u201eRotes Meer\u201c, die wir mit euren pers\u00f6nlichen Bildern gestalten werden. Viele unserer Tauchg\u00e4ste sind schon ein Red Sea PARTner und mit ein wenig Gl\u00fcck k\u00f6nnt auch ihr euch auf unserem Gem\u00e4lde verewigen.<\/p><p class=\"p1\"><b>Wie kann ich gewinnen?<\/b><\/p><p class=\"p1\">Unten findet ihr ein Formular, welches ihr mit euren Daten und der L\u00f6sung des R\u00e4tsels ausf\u00fcllen m\u00fcsst.<\/p><p class=\"p1\">Bitte f\u00fcgt auch ein Bild an, welches, sofern ihr gewinnt, auf unserer Red Sea PARTner Seite erscheinen soll.<\/p><p class=\"p1\"><b>Was muss ich sonst noch wissen?<\/b><\/p><p class=\"p1\">1. Einsendeschluss ist jeweils der darauffolgende Tag 10 Uhr.<\/p><p class=\"p1\">2. Eure erste Einsendung z\u00e4hlt.<\/p><p class=\"p1\">3. Bekommen wir mehr als eine richtige Einsendung, entscheidet das Los.<\/p><p class=\"p1\">3. Das R\u00e4tsel selbst l\u00f6sen wir einen Tag sp\u00e4ter im gleichen Beitrag auf und geben auch bekannt, wer sich einen Platz auf unserem Red Sea PARTner Gem\u00e4lde ergattert hat.<\/p><p class=\"p1\">Und jetzt w\u00fcnschen wir euch viel Erfolg beim R\u00e4tseln!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d207b31 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d207b31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378bb653 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-wp-widget-wpforms-widget\" data-id=\"378bb653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-wpforms-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-11903\"><form id=\"wpforms-form-11903\" class=\"wpforms-validate wpforms-form\" data-formid=\"11903\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/posts\/18205?wpforms_form_id=11903\" data-token=\"2421f4f3b1e4032b849d18b9932aa2fd\" data-token-time=\"1778705059\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-11903-field_25-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-11903-field_25\">Dein L\u00f6sungscode <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-11903-field_25\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][25]\" required><\/div><div id=\"wpforms-11903-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-11903-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Max\" required><label for=\"wpforms-11903-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-11903-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Mustermann\" required><label for=\"wpforms-11903-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-11903-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\">E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"email\" id=\"wpforms-11903-field_1\" class=\"wpforms-field-required wpforms-field-email-primary\" name=\"wpforms[fields][1][primary]\" spellcheck=\"false\" required><label for=\"wpforms-11903-field_1\" class=\"wpforms-field-sublabel after\">Email<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"email\" id=\"wpforms-11903-field_1-secondary\" class=\"wpforms-field-email-secondary wpforms-field-required\" data-rule-confirm=\"#wpforms-11903-field_1\" name=\"wpforms[fields][1][secondary]\" spellcheck=\"false\" required><label for=\"wpforms-11903-field_1-secondary\" class=\"wpforms-field-sublabel after\">Confirm Email<\/label><\/div><\/div><div class=\"wpforms-field-description\">Bitte gebe deine Mailadresse 2x an. Jeder kann Fehler machen. Bei einer irrt\u00fcmlich falsch eingegebenen Mailadresse k\u00f6nnen wir dir leider nicht antworten. DANKE<\/div><\/div><div id=\"wpforms-11903-field_26-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-11903-field_26\">File Upload <span class=\"wpforms-required-label\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"26\"\n\t\tdata-form-id=\"11903\"\n\t\tdata-input-name=\"wpforms_11903_26\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\t\tdata-max-size=\"536870912\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"536870912\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-11903-field_26\"\n\t\tname=\"wpforms_11903_26\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-11903-field_27-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"27\"><label class=\"wpforms-field-label\">Einverst\u00e4ndnis zur Ver\u00f6ffentlichung meines Fotos <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-11903-field_27\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-11903-field_27_1\" name=\"wpforms[fields][27][]\" value=\"Ich erkl\u00e4re mich im Falle eines Gewinnes mit der Ver\u00f6ffentlichung meines Fotos auf der Red Sea PARTner Seite einverstanden\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11903-field_27_1\">Ich erkl\u00e4re mich im Falle eines Gewinnes mit der Ver\u00f6ffentlichung meines Fotos auf der Red Sea PARTner Seite einverstanden<\/label><\/li><\/ul><\/div><div id=\"wpforms-11903-field_8-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"8\"><label class=\"wpforms-field-label\">DSGVO-Einverst\u00e4ndnis <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-11903-field_8\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-11903-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Ich willige ein, dass diese Website meine \u00fcbermittelten Informationen speichert, so dass meine Anfrage beantwortet werden kann.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11903-field_8_1\">Ich willige ein, dass diese Website meine \u00fcbermittelten Informationen speichert, so dass meine Anfrage beantwortet werden kann.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-11903-field-hp\" class=\"wpforms-field-label\">Email<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-11903-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"11903\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/18205\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-11903\" class=\"wpforms-submit\" data-alt-text=\"Senden...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc151e6 elementor-widget elementor-widget-image\" data-id=\"bc151e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-1024x682.jpg\" class=\"attachment-large size-large wp-image-15489\" alt=\"Unterwasser\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-1024x682.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-300x200.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-768x511.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-1536x1023.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung-174x116.jpg 174w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Red-Sea-Partner-Raetsel-Olaf-Mayr-Spanische-Taenzerin-Aufloesung.jpg 1984w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fc5367 elementor-widget elementor-widget-text-editor\" data-id=\"54fc5367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die L\u00f6sung des gestrigen Red Sea PARTner R\u00e4tsels lautet:<\/p>\n<p>D4, E1, E3, G1, G3, G5<\/p>\n<p>Der Gewinner des gestrigen R\u00e4tsels ist:<\/p>\n<p class=\"p1\">Rainer Lorenz<\/p>\n<p>Herzlichen Gl\u00fcckwunsch! In K\u00fcrze bist auf unserer <a href=\"https:\/\/redseapartner.com\/\" target=\"_blank\" rel=\"noopener\">Red Sea Partner Karte<\/a> mit deinem Bild verewigt!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4916817c elementor-widget elementor-widget-text-editor\" data-id=\"4916817c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c4gypten, Rotes Meer, Hurghada, Deutsche Tauchschule, James &amp; Mac Diving Center \u2013 Fotonachweis: Olaf Mayr<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Das Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin Diese Unterwasser Sch\u00f6nheit ist eine Spanische T\u00e4nzerin. Sie geh\u00f6rt zu den Nacktschnecken und macht ihrem Namen alle Ehre wenn sie unterwegs ist. Diese Nacktschnecke besitzt eine erstaunliche F\u00e4higkeit sich mit\u00a0wellenf\u00f6rmigen Bewegungen ihres Mantels im Wasser fortzubewegen, welches ihr den Popul\u00e4rnamen \u201eSpanische T\u00e4nzerin\u201c verliehen hat. Sie ist meist nachtaktiv und im Schein der Taucherlampe vollf\u00fchrt sie\u00a0einen anmutigen Tanz. Kommen wir nun aber zu unserem R\u00e4tsel: F\u00fcr das folgende R\u00e4tsel seht ihr 2 Bilder, links&hellip;<\/p>","protected":false},"author":7,"featured_media":15491,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[360,359,234,538],"class_list":["post-18205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-rotes-meer","tag-quiz","tag-raetsel","tag-red-sea-partner","tag-spanische-taenzerin","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center<\/title>\n<meta name=\"description\" content=\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center\" \/>\n<meta property=\"og:description\" content=\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/\" \/>\n<meta property=\"og:site_name\" content=\"James &amp; Mac Diving Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jamesandmac\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-14T08:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer-1024x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sir Mac\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:site\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sir Mac\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/\"},\"author\":{\"name\":\"Sir Mac\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/65290b8d2396543178d184f45630a40f\"},\"headline\":\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin\",\"datePublished\":\"2021-04-13T06:00:00+00:00\",\"dateModified\":\"2021-04-14T08:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png\",\"keywords\":[\"Quiz\",\"R\u00e4tsel\",\"Red Sea Partner\",\"Spanische T\u00e4nzerin\"],\"articleSection\":[\"Blog Rotes Meer\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/\",\"name\":\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png\",\"datePublished\":\"2021-04-13T06:00:00+00:00\",\"dateModified\":\"2021-04-14T08:21:55+00:00\",\"description\":\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png\",\"width\":4000,\"height\":3000,\"caption\":\"Unterwasser-Hurghada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/en\\\/red-sea-partner-raetsel-spanische-taenzerin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/james-mac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog Rotes Meer\",\"item\":\"https:\\\/\\\/james-mac.com\\\/en\\\/category\\\/blog-rotes-meer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"name\":\"James &amp; Mac Diving Center\",\"description\":\"Red sea diving since 1987\",\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/james-mac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\",\"name\":\"James & Mac\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"James & Mac\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jamesandmac\\\/\",\"https:\\\/\\\/x.com\\\/James_Mac_HRG\",\"https:\\\/\\\/www.instagram.com\\\/jamesundmacdiving\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/james1987mac\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/65290b8d2396543178d184f45630a40f\",\"name\":\"Sir Mac\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g\",\"caption\":\"Sir Mac\"},\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/author\\\/20sirmac20\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center","description":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/","og_locale":"en_GB","og_type":"article","og_title":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center","og_description":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!","og_url":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/","og_site_name":"James &amp; Mac Diving Center","article_publisher":"https:\/\/www.facebook.com\/jamesandmac\/","article_published_time":"2021-04-13T06:00:00+00:00","article_modified_time":"2021-04-14T08:21:55+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer-1024x768.png","type":"image\/png"}],"author":"Sir Mac","twitter_card":"summary_large_image","twitter_creator":"@James_Mac_HRG","twitter_site":"@James_Mac_HRG","twitter_misc":{"Written by":"Sir Mac","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#article","isPartOf":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/"},"author":{"name":"Sir Mac","@id":"https:\/\/james-mac.com\/#\/schema\/person\/65290b8d2396543178d184f45630a40f"},"headline":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin","datePublished":"2021-04-13T06:00:00+00:00","dateModified":"2021-04-14T08:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"image":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png","keywords":["Quiz","R\u00e4tsel","Red Sea Partner","Spanische T\u00e4nzerin"],"articleSection":["Blog Rotes Meer"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/","url":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/","name":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - James &amp; Mac Diving Center","isPartOf":{"@id":"https:\/\/james-mac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#primaryimage"},"image":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png","datePublished":"2021-04-13T06:00:00+00:00","dateModified":"2021-04-14T08:21:55+00:00","description":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin - Jede Woche testen wir eure R\u00e4tselkunst. Sucht die Fehler und werdet ein Red Sea PARTner!","breadcrumb":{"@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#primaryimage","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/01\/Beitragsbild-Red-Sea-Partner-Raetsel-Spanish-Dancer.png","width":4000,"height":3000,"caption":"Unterwasser-Hurghada"},{"@type":"BreadcrumbList","@id":"https:\/\/james-mac.com\/en\/red-sea-partner-raetsel-spanische-taenzerin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/james-mac.com\/"},{"@type":"ListItem","position":2,"name":"Blog Rotes Meer","item":"https:\/\/james-mac.com\/en\/category\/blog-rotes-meer\/"},{"@type":"ListItem","position":3,"name":"Red Sea PARTner R\u00e4tsel: Spanische T\u00e4nzerin"}]},{"@type":"WebSite","@id":"https:\/\/james-mac.com\/#website","url":"https:\/\/james-mac.com\/","name":"James &amp; Mac Diving Center","description":"Red sea diving since 1987","publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/james-mac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/james-mac.com\/#organization","name":"James &amp; Mac","url":"https:\/\/james-mac.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"James & Mac"},"image":{"@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jamesandmac\/","https:\/\/x.com\/James_Mac_HRG","https:\/\/www.instagram.com\/jamesundmacdiving\/","https:\/\/www.youtube.com\/user\/james1987mac"]},{"@type":"Person","@id":"https:\/\/james-mac.com\/#\/schema\/person\/65290b8d2396543178d184f45630a40f","name":"Sir Mac","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2da57efef350c52d7d9739e3d93278f8fc4415051287b49cdbddef9eb49bc776?s=96&r=g","caption":"Sir Mac"},"url":"https:\/\/james-mac.com\/en\/author\/20sirmac20\/"}]}},"_links":{"self":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/18205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/comments?post=18205"}],"version-history":[{"count":15,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/18205\/revisions"}],"predecessor-version":[{"id":18254,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/18205\/revisions\/18254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media\/15491"}],"wp:attachment":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media?parent=18205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/categories?post=18205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/tags?post=18205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}