
{"id":26057,"date":"2022-01-22T07:19:53","date_gmt":"2022-01-22T06:19:53","guid":{"rendered":"https:\/\/james-mac.com\/?p=26057"},"modified":"2022-01-22T07:19:55","modified_gmt":"2022-01-22T06:19:55","slug":"winterliche-woche-in-hurghada-im-rueckblick","status":"publish","type":"post","link":"https:\/\/james-mac.com\/en\/winterliche-woche-in-hurghada-im-rueckblick\/","title":{"rendered":"Winterliche Woche in Hurghada im R\u00fcckblick"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26057\" class=\"elementor elementor-26057\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-227703b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"227703b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4ad3dd\" data-id=\"f4ad3dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc199a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc199a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fa3966e\" data-id=\"fa3966e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f56543a elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"2f56543a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/unser-jubilaeumslogo-ihr-habt-entschieden\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Voriger<\/span><span class=\"post-navigation__prev--title\">Unser Jubil\u00e4umslogo &#8211; Ihr habt entschieden!<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/die-letzte-januarwoche-im-ueberblick\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster<\/span><span class=\"post-navigation__next--title\">Die letzte Januarwoche im \u00dcberblick<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50289923 elementor-widget elementor-widget-shortcode\" data-id=\"50289923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-657f44db elementor-widget elementor-widget-spacer\" data-id=\"657f44db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd68d7e elementor-widget elementor-widget-heading\" data-id=\"1dd68d7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Winterliche Woche in Hurghada im R\u00fcckblick<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51b9a289 elementor-widget elementor-widget-text-editor\" data-id=\"51b9a289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Auch in dieser Woche waren unsere Tauchlehrer wieder auf dem Roten Meer unterwegs und hatten von ihren <a href=\"https:\/\/james-mac.com\/en\/taegliche-tauchausfahrten\/\" target=\"_blank\" rel=\"noopener\">Diving Trips<\/a> einiges zu berichten. Bei uns in Hurghada ist immer was los und auch anderswo, nicht nur in \u00c4gypten passierten aufregende Dinge. Hier ist eine winterliche Woche in Hurghada im R\u00fcckblick:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a6f4415 elementor-widget elementor-widget-spacer\" data-id=\"4a6f4415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ff0f58 elementor-widget elementor-widget-image\" data-id=\"5ff0f58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-1024x768.jpg\" class=\"attachment-large size-large wp-image-11256\" alt=\"Winterliche Woche in Hurghada im R\u00fcckblick\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz-155x116.jpg 155w, https:\/\/james-mac.com\/wp-content\/uploads\/2020\/09\/Adlerrochen-Kai-Walz.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2280868d elementor-widget elementor-widget-spacer\" data-id=\"2280868d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4556563b elementor-widget elementor-widget-heading\" data-id=\"4556563b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sonnenschein und winterliches Tauchvergn\u00fcgen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7b21f elementor-widget elementor-widget-text-editor\" data-id=\"2a7b21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nicht nur in Deutschland herrschen winterliche Temperaturen, auch in \u00c4gypten ist die kalte Jahreszeit voll im Gange. Nachts wird es ziemlich frisch und ohne Jacke geht abends auch hier momentan nichts. Aber die Sonne lacht vom Himmel und ohne Wind kann man es tags\u00fcber auf dem Tauchboot auch wunderbar aushalten, teilweise sogar in Badekleidung. Das Wasser hat 22 Grad, das ist zwar keine Badewannen-Temperatur, aber vom Eistauchen sind wir dennoch weit entfernt.\u00a0<\/p><p>Wie immer in den Wintermonaten gilt: Winterzeit ist Fanadirzeit. Die gro\u00dfen Rochen tummeln sich vornehmlich s\u00fcdlich von <a href=\"https:\/\/james-mac.com\/en\/gut-gelaunt-gings-uebers-rote-meer\/\" target=\"_blank\" rel=\"noopener\">Fanadir<\/a> Dacht und da zieht es uns hin. Beim Anblick von manchmal \u00fcber 20 majest\u00e4tischen gro\u00dfen Tieren, die im Sand mehr oder weniger versteckt liegen, vergisst man auch mal die Umgebungstemperatur. Vor allem auch dann, wenn man von Adlerrochen begleitet wird, denn auch sie begegnen uns vermehrt um diese Jahreszeit.<\/p><p>Ein weiterer Vorteil vom Tauchen im Roten Meer um diese Jahreszeit ist, dass man viele Pl\u00e4tze ganz f\u00fcr sich hat, die normalerweise sehr begehrt sind. So kann man sich momentan in <a href=\"https:\/\/james-mac.com\/en\/ein-froehlicher-ausflug-zwischen-die-inseln\/\" target=\"_blank\" rel=\"noopener\">Shaab Abu Ramada<\/a> alleine austoben und sowohl auf der Ost- als auch auf der Westseite in aller Seelenruhe st\u00f6bern. So finden unsere Taucher auch mal ein Schneckchen, das sie sonst glatt \u00fcbersehen h\u00e4tten.\u00a0<\/p><p>Wer einmal richtig winterlich unterwegs sein m\u00f6chte, der macht einen Tauchgang an der <a href=\"https:\/\/james-mac.com\/en\/unterwegs-an-einem-schoenen-wintertag\/\" target=\"_blank\" rel=\"noopener\">Balena<\/a>.\u00a0Da nah an der K\u00fcste wenig Wasserbewegung herrscht, ist es nochmal ein bisschen k\u00fchler als drau\u00dfen im offenen Meer. Aber die Wassertemperatur tritt v\u00f6llig in den Hintergrund, wenn man die ganze Fisch- und Korallenpracht an unserem kleinen \u201eHauswrack\u201c sieht. Unz\u00e4hlige Schnecken, Schwarmfisch ohne Ende, Graue Mur\u00e4nen, Fledermausfische, alles ist hier in \u00dcberzahl vorhanden. Auch bei unseren G\u00e4sten herrschte wieder absolute Begeisterung.<\/p><p>Auch wenn es im Roten Meer mal nicht ganz so kuschelig ist, Tauchen ist hier auch im Winter absolut lohnenswert!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae72246 elementor-widget elementor-widget-spacer\" data-id=\"ae72246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-620f890 elementor-widget elementor-widget-image\" data-id=\"620f890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"636\" height=\"477\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Shark-Finning-Wikipedia-NOAA-4x3-1.jpg\" class=\"attachment-large size-large wp-image-26074\" alt=\"\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Shark-Finning-Wikipedia-NOAA-4x3-1.jpg 636w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Shark-Finning-Wikipedia-NOAA-4x3-1-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Shark-Finning-Wikipedia-NOAA-4x3-1-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Shark-Finning-Wikipedia-NOAA-4x3-1-155x116.jpg 155w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e50955 elementor-widget elementor-widget-spacer\" data-id=\"65e50955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24582ea8 elementor-widget elementor-widget-heading\" data-id=\"24582ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wichtige Petition gegen Shark Finning l\u00e4uft noch<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-054a068 elementor-widget elementor-widget-text-editor\" data-id=\"054a068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine sehr wichtige Kampagne, die wir gerne unterst\u00fctzen, ist momentan die Unterschriftensammlung f\u00fcr ein EU-weites Handelsverbot mit abgeschnittenen Hai-Flossen, \u201e<a href=\"https:\/\/www.stop-finning-eu.org\/de\/\" target=\"_blank\" rel=\"noopener\">Stop Finning \u2013 Stop the Trade<\/a>\u201d. Bis zum 31.01.22 werden 1.000.000 Unterschriften ben\u00f6tigt, um mit dem Vorschlag zur Gesetzes\u00e4nderung in Richtung Handelsverbot angeh\u00f6rt zu werden. Das Ziel ist seit letzter Woche bereits erreicht, doch trotzdem ist nach wie vor jede Unterschrift wichtig, denn je mehr Leute unterzeichnen, desto deutlicher wird die Dringlichkeit dieser Aktion.<\/p><p>Das Abtrennen von Flossen an Bord von EU-Schiffen und in EU-Gew\u00e4ssern ist verboten. Haie m\u00fcssen inklusive Flossen an Land gebracht werden. Dennoch geh\u00f6rt die EU zu den gr\u00f6\u00dften Exporteuren von Flossen und ist ein bedeutender Transitknotenpunkt f\u00fcr den weltweiten Handel mit Flossen.<\/p><p>Da auf See nur selten Kontrollen stattfinden, werden Flossen weiterhin illegal zur\u00fcckbehalten, umgeladen oder in der EU angelandet. Das gro\u00dfe Ziel ist es, den Handel mit Flossen in der EU beenden. Dazu geh\u00f6rt die Ein-, Aus- und Durchfuhr von Flossen, die sich nicht am K\u00f6rper des Tiers befinden.<\/p><p><a href=\"https:\/\/de.wikipedia.org\/wiki\/Shark-Finning\" target=\"_blank\" rel=\"noopener\">Shark-Finning<\/a>\u00a0 bezeichnet das Abtrennen der R\u00fcckenflosse und anderer Flossen von Haien und die anschlie\u00dfende Entsorgung des Tieres im Meer. Der Hai wird daf\u00fcr normalerweise nicht get\u00f6tet, er ist danach jedoch schwimmunf\u00e4hig und sinkt zu Boden, wo qualvoll stirbt.<\/p><p>Weil das Shark-Finning auf dem Meer stattfindet, m\u00fcssen die Fischer nur die Flossen an Land transportieren und werfen den \u201erestlichen\u201c Hai, dessen Fleisch nicht wertvoll genug ist, ins Meer zur\u00fcck. Die Flossen werden dann an Land getrocknet und verkauft. Es gibt keinerlei Einschr\u00e4nkungen. Alle gefangenen Haie werden \u201egefinnt\u201d und verenden danach. Das &#8222;Finnen&#8220; ist weltweit verbreitet und wird nicht \u00fcberwacht.<\/p><p>Auch in \u00c4gypten machen Fischer trotz des <a href=\"https:\/\/www.tauchen.de\/umweltschutz\/haifang-vom-jaeger-zum-gejagten\/\" target=\"_blank\" rel=\"noopener\">Verbots von Haifischfang und -handel<\/a> und der Unterzeichnung eines internationalen Abkommens zum Schutz der Haie massenhaft Jagd auf sie. Ganz sch\u00f6n unklug eigentlich in einem Land, das vom Tauchtourismus lebt!<span class=\"c-message__edited_label\" dir=\"ltr\" data-sk=\"tooltip_parent\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7e7ad elementor-widget elementor-widget-spacer\" data-id=\"2a7e7ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44a3f07 elementor-widget elementor-widget-image\" data-id=\"44a3f07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-26067\" alt=\"\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-2048x1536.jpg 2048w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Loecher-Krake-Screenshot-4x3-1-155x116.jpg 155w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58c16ed5 elementor-widget elementor-widget-spacer\" data-id=\"58c16ed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4bfbb elementor-widget elementor-widget-heading\" data-id=\"7d4bfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Faszinierende Aufnahmen einer L\u00f6cherkrake<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ece2189 elementor-widget elementor-widget-text-editor\" data-id=\"ece2189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Letzte Woche gab es die absolut seltene und unglaubliche Sichtung eines <a href=\"https:\/\/edition.cnn.com\/videos\/travel\/2022\/01\/15\/rare-octopus-blanket-great-barrier-reef-elliot-island-orig-mg-kj.cnn\/video\/playlists\/atv-trending-videos\/\" target=\"_blank\" rel=\"noopener\">freischwimmenden L\u00f6cherkraken<\/a>, die wir euch nicht vorenthalten wollen. Zwar hat man der L\u00f6cherkrake nicht im Roten Meer, sondern in Australien gesichtet, aber wer wei\u00df, vielleicht taucht ja bei uns auch mal einer auf.<\/p><p>Es handelt sich hierbei um einen \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=RyDsFedE4vs\" target=\"_blank\" rel=\"noopener\">Blanket Octopus<\/a>\u201d, also ein Exemplar aus der Gattung der sogenannten Deckenkraken oder L\u00f6cherkraken. Der Name ist auf die langen, transparenten Schwimmh\u00e4ute zur\u00fcckzuf\u00fchren, die die seitlichen und r\u00fcckw\u00e4rtigen Arme der erwachsenen Weibchen verbinden. Die anderen Arme sind viel k\u00fcrzer und haben keine Schwimmh\u00e4ute. L\u00f6cherkraken gibt es \u00fcberall auf der Welt in tropischen und subtropischen Meeren. Man sieht sie jedoch leider fast nie.<\/p><p>Die weiblichen L\u00f6cherkraken k\u00f6nnen bis zu 2 m lang werden, w\u00e4hrend die <a href=\"https:\/\/www.spiegel.de\/wissenschaft\/natur\/ungleicher-sex-loecherkraken-haben-die-mickrigsten-maennchen-a-233082.html\" target=\"_blank\" rel=\"noopener\">M\u00e4nnchen<\/a> nur knapp 3 cm lang sind. Das ist der gr\u00f6\u00dfte geschlechtsspezifische Gr\u00f6\u00dfenunterschied, den man jemals beobachtet hat. Die M\u00e4nnchen haben einen gro\u00dfen Arm in einem kugelf\u00f6rmigen Beutel, der f\u00fcr die Paarung modifiziert wurde. W\u00e4hrend der Paarung wird dieser Arm abgetrennt und vom Weibchen in ihrer Mantelh\u00f6hle aufbewahrt, bis er zur Befruchtung verwendet wird. Das M\u00e4nnchen stirbt mit ziemlicher Sicherheit kurz nach der Paarung. Die M\u00e4nnchen konkurrieren miteinander; man hat mehrere m\u00e4nnliche Arme in der Mantelh\u00f6hle der Weibchen gefunden. Die Weibchen tragen mehr als 100 000 Eier, die an einem wurstf\u00f6rmigen Kalksekret an der Basis der R\u00fcckenarme h\u00e4ngen und vom Weibchen bis zum Schl\u00fcpfen getragen werden.<\/p><p>Die Kraken sind immun gegen die giftige portugiesische Galerie, deren Tentakel die L\u00f6cherkraken abrei\u00dfen und zu Angriffs- und Verteidigungszwecken einsetzen. Wie viele andere Kraken verwendet auch der L\u00f6cherkrake Tinte, um potenzielle Fressfeinde einzusch\u00fcchtern. Au\u00dferdem entfaltet das Weibchen bei Bedrohung seine gro\u00dfen netzartigen Membranen, die sich im Wasser ausbreiten und wellenf\u00f6rmig aufbl\u00e4hen, was seine scheinbare Gr\u00f6\u00dfe stark erh\u00f6ht. Zu den Fressfeinden der Gew\u00f6hnlichen Riesenkrake geh\u00f6ren der Blauhai, der Thunfisch und der Schnapper.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b431e0a elementor-widget elementor-widget-spacer\" data-id=\"b431e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef8f561 elementor-widget elementor-widget-image\" data-id=\"1ef8f561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-20681\" alt=\"\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1-155x116.jpg 155w, https:\/\/james-mac.com\/wp-content\/uploads\/2021\/06\/Mumie-Sarkophag-Wikipedia-Joshua-Sherurcij-4x3-1.jpg 2000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13ceb87c elementor-widget elementor-widget-spacer\" data-id=\"13ceb87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-389c9a69 elementor-widget elementor-widget-heading\" data-id=\"389c9a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Griechische Mumie bei Assuan entdeckt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-655c917 elementor-widget elementor-widget-text-editor\" data-id=\"655c917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wie Arch\u00e4ologen letzte Woche bekannt gaben, hat man k\u00fcrzlich in Assuan ein Grab aus der griechisch-r\u00f6mischen Zeit mit einer <a href=\"https:\/\/greekreporter.com\/2022\/01\/19\/greek-mummy-aswan-egypt\/\" target=\"_blank\" rel=\"noopener\">griechischen Mumie<\/a> ausgegraben. Als zus\u00e4tzliche, \u00e4u\u00dferst ungew\u00f6hnliche Entdeckung fanden die Arch\u00e4ologen eine Kupfertafel mit dem Namen des Mannes &#8211; Nikostratos &#8211; in der N\u00e4he seines K\u00f6rpers. Den erstaunlichen Fund machten sie im Rahmen von Ausgrabungen der \u00c4gyptisch-Italienischen Mission im Westen Assuans, in der N\u00e4he des Aga-Khan-Mausoleums. Obwohl der Grabkomplex in der Antike gepl\u00fcndert worden war, war die Mumie des griechischen Mannes unversehrt. Bei der Mumie hat man Grabbeigaben, wie zum Beispiel kunstvolle T\u00f6pferwaren gefunden.<\/p><p>Am Eingang des Grabes fand man einen Opferaltar mit \u00dcberresten von Tierknochen. Bei dem Grab handelt es sich anscheinend um ein gro\u00dfes Familiengrab, das insgesamt <a href=\"https:\/\/www.ancient-origins.net\/news-history-archaeology\/greco-roman-tomb-0016320\" target=\"_blank\" rel=\"noopener\">zwanzig Mumien<\/a> aus der griechisch-r\u00f6mischen Zeit enth\u00e4lt. In der Halle, gegen\u00fcber dem Eingang des Grabes fanden die Forscher einen Terrakotta-Sarkophag mit der Mumie eines Kindes und eine Kartonage. Hierbei handelt es sich um eine Art alt\u00e4gyptische Totenmaske, die aus mit Gips \u00fcberzogenen Leinen- oder Papyrusschichten besteht.\u00a0<\/p><p>Der Raum f\u00fchrt zu vier Grabkammern, die aus dem nat\u00fcrlichen Felsgestein herausgeschnitten worden waren und in denen die meisten Mumien beigesetzt waren. Eine Treppe, die teilweise von geschnitzten Bl\u00f6cken flankiert und von einem Lehmziegelgew\u00f6lbe bedeckt ist, f\u00fchrt zum <a href=\"https:\/\/www.heritagedaily.com\/2022\/01\/greco-roman-tomb-containing-twenty-mummies-discovered-near-aswan\/142530\" target=\"_blank\" rel=\"noopener\">Eingang<\/a>. Dieser war von einem komplexen System aus Platten und Steinbl\u00f6cken \u00fcber der Treppe umschlossen. Am Eingang hat man einen gro\u00dfen Opfertisch oder Altar in Bruchst\u00fccken gefunden, auf dessen Oberfl\u00e4che noch deutlich Hieroglyphen zu erkennen sind. Dar\u00fcber hinaus wurden in dem griechisch-r\u00f6mischen Grab auch einige Holzstatuen gefunden.\u00a0<\/p><p>Arch\u00e4ologen fanden die Mumie des Mannes an der Ostwand des Bauwerks. Sie glauben, dass sich sein Leichnam urspr\u00fcnglich in dem Grab befand, das kurz darauf unter dem rechteckigen Bauwerk freigelegt wurde. Anscheinend hatten Pl\u00fcnderer in der Antike die Mumie aus dem Familiengrab geholt und dann hier abgelegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d43694b elementor-widget elementor-widget-spacer\" data-id=\"d43694b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b337408 elementor-widget elementor-widget-heading\" data-id=\"b337408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Winterliche Woche in Hurghada im R\u00fcckblick<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69fa36c3 elementor-widget elementor-widget-text-editor\" data-id=\"69fa36c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das war die winterliche Woche in Hurghada im R\u00fcckblick. N\u00e4chste Woche gibt es wieder aktuelle Neuigkeiten von \u00c4gypten und anderswo <a href=\"https:\/\/james-mac.com\/en\/news-3\/\" target=\"_blank\" rel=\"noopener\">zu berichten<\/a>, wir halten euch auf dem Laufenden!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4151c811 elementor-widget elementor-widget-text-editor\" data-id=\"4151c811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Winterliche Woche in Hurghada im R\u00fcckblick, James &amp; Mac Diving Center \u2013 Fotonachweise: James &amp; Mac, Kai Walz,\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Winterliche Woche in Hurghada im R\u00fcckblick Auch in dieser Woche waren unsere Tauchlehrer wieder auf dem Roten Meer unterwegs und hatten von ihren Tauchausfahrten einiges zu berichten. Bei uns in Hurghada ist immer was los und auch anderswo, nicht nur in \u00c4gypten passierten aufregende Dinge. Hier ist eine winterliche Woche in Hurghada im R\u00fcckblick: Sonnenschein und winterliches Tauchvergn\u00fcgen Nicht nur in Deutschland herrschen winterliche Temperaturen, auch in \u00c4gypten ist die kalte Jahreszeit voll im Gange. Nachts wird es ziemlich frisch&hellip;<\/p>","protected":false},"author":4,"featured_media":26058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[837,136,170,135,413,355],"class_list":["post-26057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-rotes-meer","tag-837","tag-aegypten","tag-hurghada","tag-rotes-meer","tag-rueckblick","tag-wochenrueckblick","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center<\/title>\n<meta name=\"description\" content=\"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/james-mac.com\/en\/winterliche-woche-in-hurghada-im-rueckblick\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center\" \/>\n<meta property=\"og:description\" content=\"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/james-mac.com\/en\/winterliche-woche-in-hurghada-im-rueckblick\/\" \/>\n<meta property=\"og:site_name\" content=\"James &amp; Mac Diving Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jamesandmac\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-22T06:19:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-22T06:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ameli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:site\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ameli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/\"},\"author\":{\"name\":\"Ameli\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\"},\"headline\":\"Winterliche Woche in Hurghada im R\u00fcckblick\",\"datePublished\":\"2022-01-22T06:19:53+00:00\",\"dateModified\":\"2022-01-22T06:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/\"},\"wordCount\":1449,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg\",\"keywords\":[\"2022\",\"\u00c4gypten\",\"Hurghada\",\"Rotes Meer\",\"R\u00fcckblick\",\"Wochenr\u00fcckblick\"],\"articleSection\":[\"Blog Rotes Meer\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/\",\"name\":\"Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg\",\"datePublished\":\"2022-01-22T06:19:53+00:00\",\"dateModified\":\"2022-01-22T06:19:55+00:00\",\"description\":\"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#primaryimage\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Winterliche Woche in Hurghada im R\u00fcckblick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/winterliche-woche-in-hurghada-im-rueckblick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/james-mac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog Rotes Meer\",\"item\":\"https:\\\/\\\/james-mac.com\\\/en\\\/category\\\/blog-rotes-meer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Winterliche Woche in Hurghada im R\u00fcckblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"name\":\"James & Mac Diving Center\",\"description\":\"Red sea diving since 1987\",\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/james-mac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\",\"name\":\"James & Mac\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JM-Logo-Neu-Ohne-Schrift-Klein.png\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JM-Logo-Neu-Ohne-Schrift-Klein.png\",\"width\":400,\"height\":193,\"caption\":\"James & Mac\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jamesandmac\\\/\",\"https:\\\/\\\/x.com\\\/James_Mac_HRG\",\"https:\\\/\\\/www.instagram.com\\\/jamesundmacdiving\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/james1987mac\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\",\"name\":\"Ameli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"caption\":\"Ameli\"},\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/author\\\/ameli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center","description":"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/james-mac.com\/en\/winterliche-woche-in-hurghada-im-rueckblick\/","og_locale":"en_GB","og_type":"article","og_title":"Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center","og_description":"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.","og_url":"https:\/\/james-mac.com\/en\/winterliche-woche-in-hurghada-im-rueckblick\/","og_site_name":"James &amp; Mac Diving Center","article_publisher":"https:\/\/www.facebook.com\/jamesandmac\/","article_published_time":"2022-01-22T06:19:53+00:00","article_modified_time":"2022-01-22T06:19:55+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg","type":"image\/jpeg"}],"author":"Ameli","twitter_card":"summary_large_image","twitter_creator":"@James_Mac_HRG","twitter_site":"@James_Mac_HRG","twitter_misc":{"Written by":"Ameli","Estimated reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#article","isPartOf":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/"},"author":{"name":"Ameli","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4"},"headline":"Winterliche Woche in Hurghada im R\u00fcckblick","datePublished":"2022-01-22T06:19:53+00:00","dateModified":"2022-01-22T06:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/"},"wordCount":1449,"commentCount":2,"publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"image":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg","keywords":["2022","\u00c4gypten","Hurghada","Rotes Meer","R\u00fcckblick","Wochenr\u00fcckblick"],"articleSection":["Blog Rotes Meer"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/","url":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/","name":"Winterliche Woche in Hurghada im R\u00fcckblick - James &amp; Mac Diving Center","isPartOf":{"@id":"https:\/\/james-mac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#primaryimage"},"image":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg","datePublished":"2022-01-22T06:19:53+00:00","dateModified":"2022-01-22T06:19:55+00:00","description":"Winterliche Woche in Hurghada im R\u00fcckblick. Auch diese Woche blicken wir auf Dinge zur\u00fcck, die in \u00c4gypten und anderswo passiert sind.","breadcrumb":{"@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#primaryimage","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2022\/01\/JM-Lulu-Ausfahrt-Hafen-Jan-22-Foto-Bini-4x3-1-scaled.jpg","width":2560,"height":1920,"caption":"Winterliche Woche in Hurghada im R\u00fcckblick"},{"@type":"BreadcrumbList","@id":"https:\/\/james-mac.com\/winterliche-woche-in-hurghada-im-rueckblick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/james-mac.com\/"},{"@type":"ListItem","position":2,"name":"Blog Rotes Meer","item":"https:\/\/james-mac.com\/en\/category\/blog-rotes-meer\/"},{"@type":"ListItem","position":3,"name":"Winterliche Woche in Hurghada im R\u00fcckblick"}]},{"@type":"WebSite","@id":"https:\/\/james-mac.com\/#website","url":"https:\/\/james-mac.com\/","name":"James &amp; Mac Diving Center","description":"Red sea diving since 1987","publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/james-mac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/james-mac.com\/#organization","name":"James &amp; Mac","url":"https:\/\/james-mac.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/03\/JM-Logo-Neu-Ohne-Schrift-Klein.png","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/03\/JM-Logo-Neu-Ohne-Schrift-Klein.png","width":400,"height":193,"caption":"James & Mac"},"image":{"@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jamesandmac\/","https:\/\/x.com\/James_Mac_HRG","https:\/\/www.instagram.com\/jamesundmacdiving\/","https:\/\/www.youtube.com\/user\/james1987mac"]},{"@type":"Person","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4","name":"Ameli","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","caption":"Ameli"},"url":"https:\/\/james-mac.com\/en\/author\/ameli\/"}]}},"_links":{"self":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/26057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/comments?post=26057"}],"version-history":[{"count":47,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/26057\/revisions"}],"predecessor-version":[{"id":26123,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/26057\/revisions\/26123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media\/26058"}],"wp:attachment":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media?parent=26057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/categories?post=26057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/tags?post=26057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}