{"id":40131,"date":"2023-08-10T14:35:33","date_gmt":"2023-08-10T12:35:33","guid":{"rendered":"https:\/\/james-mac.com\/?p=40131"},"modified":"2023-08-11T07:34:19","modified_gmt":"2023-08-11T05:34:19","slug":"der-inoffizielle-tag-des-napoleon-lippfischs","status":"publish","type":"post","link":"https:\/\/james-mac.com\/en\/der-inoffizielle-tag-des-napoleon-lippfischs\/","title":{"rendered":"Der inoffizielle Tag des Napoleon Lippfischs"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"40131\" class=\"elementor elementor-40131\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6d6e063c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d6e063c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37741d0b\" data-id=\"37741d0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-element elementor-element-277ee274 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"277ee274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/ein-super-schoener-tag-zwischen-den-inseln\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-caret-left\"><\/i><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Voriger<\/span><span class=\"post-navigation__prev--title\">Ein super sch\u00f6ner Tag zwischen den Inseln<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/entspannte-pause-in-der-lagune\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster<\/span><span class=\"post-navigation__next--title\">Entspannte Pause in der Lagune<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1fa56b elementor-widget elementor-widget-shortcode\" data-id=\"3b1fa56b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b91b923 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"3b91b923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51fc7473 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"51fc7473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der inoffizielle Tag des Napoleon Lippfischs und damit hei\u00dft es Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023!<\/p><p>Unsere\u00a0<a href=\"https:\/\/james-mac.com\/en\/unsere-basis\/orientierung-team\/\" target=\"_blank\" rel=\"noopener\">Tauchguides<\/a>\u00a0berichten an dieser Stelle jeden Tag von den Sichtungen der kleinen und auch gro\u00dfen Sch\u00e4tze, die unser sch\u00f6nes\u00a0Rotes Meer\u00a0zu bieten hat. Au\u00dferdem erz\u00e4hlen sie \u00fcber all das, was sie auf dem Meer und unter Wasser erlebt haben.\u00a0Auch \u00fcber die wundervollen Erlebnisse auf unseren mehrt\u00e4gigen Minisafaris halten sie euch stets auf dem Laufenden. Egal, ob Early Morning Dive oder Nachttauchgang &#8211; ihr k\u00f6nnt es mitverfolgen. Auch Wracktauchg\u00e4nge in Abu Nuhas oder an der Thistlegorm stehen auf dem Programm. Ob im Norden oder S\u00fcden, ihr seid mit an Bord!<\/p><p>Und das Beste? Unsere Berichte \u00fcber die Tauchausfahrten unserer Boote erscheinen t\u00e4glich! 365 Tage im Jahr k\u00f6nnt ihr mit uns zusammen auf die Reise gehen und im <a href=\"https:\/\/www.youtube.com\/user\/james1987mac\/videos\" target=\"_blank\" rel=\"noopener\">Roten Meer<\/a> abtauchen! Seid dabei und lasst euch immer wieder aufs Neue verzaubern. Willkommen zu unseren t\u00e4glichen Tauchausfahrten!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64c66d57 elementor-widget elementor-widget-shortcode\" data-id=\"64c66d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67d8faff elementor-widget elementor-widget-text-editor\" data-id=\"67d8faff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Berichte \u00fcber die Tauchausfahrten unserer Boote erscheinen t\u00e4glich! 365 Tage im Jahr k\u00f6nnt ihr mit uns zusammen auf die Reise gehen und im Roten Meer abtauchen! Kommt an Bord und lasst euch immer wieder aufs Neue verzaubern. Auch morgen k\u00f6nnt ihr wieder dabei sein und die Erlebnisse unserer Tauchguides mitverfolgen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27cd44b1 elementor-widget elementor-widget-text-editor\" data-id=\"27cd44b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der inoffizielle Tag des Napoleon Lippfischs, \u00c4gypten, Rotes Meer, Hurghada, Deutsche Tauchschule, Tauchen, Tauchkurse, James &amp; Mac Diving Center \u2013 Fotonachweise: James &amp; Mac Diving Center, Sven Kahlbrock, salzeproductions, Thorsten Rieck, Olaf Mayr<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-bac3349 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bac3349\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15ffa3bd\" data-id=\"15ffa3bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d13ee73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d13ee73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-105b74ce\" data-id=\"105b74ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231bcb5 elementor-widget elementor-widget-wp-widget-archives\" data-id=\"231bcb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-archives.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5>Archiv<\/h5>\t\t<label class=\"screen-reader-text\" for=\"archives-dropdown-REPLACE_TO_ID\">Archiv<\/label>\n\t\t<select id=\"archives-dropdown-REPLACE_TO_ID\" name=\"archive-dropdown\">\n\t\t\t\n\t\t\t<option value=\"\">Select Month<\/option>\n\t\t\t\t<option value='https:\/\/james-mac.com\/en\/2026\/09\/'> September 2026 &nbsp;(2)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/08\/'> August 2026 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/07\/'> July 2026 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/06\/'> June 2026 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/05\/'> May 2026 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/04\/'> April 2026 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/03\/'> March 2026 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/02\/'> February 2026 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2026\/01\/'> January 2026 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/12\/'> December 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/11\/'> November 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/10\/'> October 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/09\/'> September 2025 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/08\/'> August 2025 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/07\/'> July 2025 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/06\/'> June 2025 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/05\/'> May 2025 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/04\/'> April 2025 &nbsp;(30)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/03\/'> March 2025 &nbsp;(31)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/02\/'> February 2025 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2025\/01\/'> January 2025 &nbsp;(31)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/12\/'> December 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/11\/'> November 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/10\/'> October 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/09\/'> September 2024 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/08\/'> August 2024 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/07\/'> July 2024 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/06\/'> June 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/05\/'> May 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/04\/'> April 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/03\/'> March 2024 &nbsp;(37)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/02\/'> February 2024 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2024\/01\/'> January 2024 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/12\/'> December 2023 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/11\/'> November 2023 &nbsp;(35)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/10\/'> October 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/09\/'> September 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/08\/'> August 2023 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/07\/'> July 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/06\/'> June 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/05\/'> May 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/04\/'> April 2023 &nbsp;(40)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/03\/'> March 2023 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/02\/'> February 2023 &nbsp;(34)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2023\/01\/'> January 2023 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/12\/'> December 2022 &nbsp;(38)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/11\/'> November 2022 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/10\/'> October 2022 &nbsp;(41)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/09\/'> September 2022 &nbsp;(32)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/08\/'> August 2022 &nbsp;(26)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/07\/'> July 2022 &nbsp;(33)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/06\/'> June 2022 &nbsp;(24)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/05\/'> May 2022 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/04\/'> April 2022 &nbsp;(28)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/03\/'> March 2022 &nbsp;(21)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/02\/'> February 2022 &nbsp;(27)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2022\/01\/'> January 2022 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/12\/'> December 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/11\/'> November 2021 &nbsp;(36)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/10\/'> October 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/09\/'> September 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/08\/'> August 2021 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/07\/'> July 2021 &nbsp;(42)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/06\/'> June 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/05\/'> May 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/04\/'> April 2021 &nbsp;(45)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/03\/'> March 2021 &nbsp;(46)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/02\/'> February 2021 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2021\/01\/'> January 2021 &nbsp;(46)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/12\/'> December 2020 &nbsp;(50)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/11\/'> November 2020 &nbsp;(43)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/10\/'> October 2020 &nbsp;(44)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/09\/'> September 2020 &nbsp;(39)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/08\/'> August 2020 &nbsp;(24)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/07\/'> July 2020 &nbsp;(22)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/06\/'> June 2020 &nbsp;(19)<\/option>\n\t<option value='https:\/\/james-mac.com\/en\/2020\/01\/'> January 2020 &nbsp;(1)<\/option>\n\n\t\t<\/select>\n\n\t\t\t<script>\n( ( dropdownId ) => {\n\tconst dropdown = document.getElementById( dropdownId );\n\tfunction onSelectChange() {\n\t\tsetTimeout( () => {\n\t\t\tif ( 'escape' === dropdown.dataset.lastkey ) {\n\t\t\t\treturn;\n\t\t\t}\n\t\t\tif ( dropdown.value ) {\n\t\t\t\tdocument.location.href = dropdown.value;\n\t\t\t}\n\t\t}, 250 );\n\t}\n\tfunction onKeyUp( event ) {\n\t\tif ( 'Escape' === event.key ) {\n\t\t\tdropdown.dataset.lastkey = 'escape';\n\t\t} else {\n\t\t\tdelete dropdown.dataset.lastkey;\n\t\t}\n\t}\n\tfunction onClick() {\n\t\tdelete dropdown.dataset.lastkey;\n\t}\n\tdropdown.addEventListener( 'keyup', onKeyUp );\n\tdropdown.addEventListener( 'click', onClick );\n\tdropdown.addEventListener( 'change', onSelectChange );\n})( \"archives-dropdown-REPLACE_TO_ID\" );\n\n\/\/# sourceURL=WP_Widget_Archives%3A%3Awidget\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Der inoffizielle Tag des Napoleon Lippfischs und damit hei\u00dft es Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023! Unsere\u00a0Tauchguides\u00a0berichten an dieser Stelle jeden Tag von den Sichtungen der kleinen und auch gro\u00dfen Sch\u00e4tze, die unser sch\u00f6nes\u00a0Rotes Meer\u00a0zu bieten hat. Au\u00dferdem erz\u00e4hlen sie \u00fcber all das, was sie auf dem Meer und unter Wasser erlebt haben.\u00a0Auch \u00fcber die wundervollen Erlebnisse auf unseren mehrt\u00e4gigen Minisafaris halten sie euch stets auf dem Laufenden. Egal, ob Early Morning Dive oder Nachttauchgang &#8211; ihr&hellip;<\/p>","protected":false},"author":4,"featured_media":23918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[768,779,925,246],"class_list":["post-40131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-taegliche-tauchausfahrten","tag-einsteigertour","tag-ham-ham","tag-langnasenbueschelbarsche","tag-napoleon","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center<\/title>\n<meta name=\"description\" content=\"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/james-mac.com\/en\/der-inoffizielle-tag-des-napoleon-lippfischs\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center\" \/>\n<meta property=\"og:description\" content=\"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/james-mac.com\/en\/der-inoffizielle-tag-des-napoleon-lippfischs\/\" \/>\n<meta property=\"og:site_name\" content=\"James &amp; Mac Diving Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jamesandmac\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-10T12:35:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T05:34:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1570\" \/>\n\t<meta property=\"og:image:height\" content=\"1177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ameli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:site\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ameli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/\"},\"author\":{\"name\":\"Ameli\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\"},\"headline\":\"Der inoffizielle Tag des Napoleon Lippfischs\",\"datePublished\":\"2023-08-10T12:35:33+00:00\",\"dateModified\":\"2023-08-11T05:34:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg\",\"keywords\":[\"Einsteigertour\",\"Ham Ham\",\"Langnasenb\u00fcschelbarsche\",\"Napoleon\"],\"articleSection\":[\"T\u00e4gliche Tauchausfahrten\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/\",\"name\":\"Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg\",\"datePublished\":\"2023-08-10T12:35:33+00:00\",\"dateModified\":\"2023-08-11T05:34:19+00:00\",\"description\":\"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg\",\"width\":1570,\"height\":1177,\"caption\":\"Der inoffizielle Tag des Napoleon Lippfischs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/der-inoffizielle-tag-des-napoleon-lippfischs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/james-mac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e4gliche Tauchausfahrten\",\"item\":\"https:\\\/\\\/james-mac.com\\\/category\\\/taegliche-tauchausfahrten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Der inoffizielle Tag des Napoleon Lippfischs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"name\":\"James & Mac Diving Center\",\"description\":\"Red sea diving since 1987\",\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/james-mac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\",\"name\":\"James & Mac\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JM-Logo-Neu-Ohne-Schrift-Klein.png\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JM-Logo-Neu-Ohne-Schrift-Klein.png\",\"width\":400,\"height\":193,\"caption\":\"James & Mac\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jamesandmac\\\/\",\"https:\\\/\\\/x.com\\\/James_Mac_HRG\",\"https:\\\/\\\/www.instagram.com\\\/jamesundmacdiving\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/james1987mac\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\",\"name\":\"Ameli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"caption\":\"Ameli\"},\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/author\\\/ameli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center","description":"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/james-mac.com\/en\/der-inoffizielle-tag-des-napoleon-lippfischs\/","og_locale":"en_GB","og_type":"article","og_title":"Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center","og_description":"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!","og_url":"https:\/\/james-mac.com\/en\/der-inoffizielle-tag-des-napoleon-lippfischs\/","og_site_name":"James &amp; Mac Diving Center","article_publisher":"https:\/\/www.facebook.com\/jamesandmac\/","article_published_time":"2023-08-10T12:35:33+00:00","article_modified_time":"2023-08-11T05:34:19+00:00","og_image":[{"width":1570,"height":1177,"url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg","type":"image\/jpeg"}],"author":"Ameli","twitter_card":"summary_large_image","twitter_creator":"@James_Mac_HRG","twitter_site":"@James_Mac_HRG","twitter_misc":{"Written by":"Ameli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#article","isPartOf":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/"},"author":{"name":"Ameli","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4"},"headline":"Der inoffizielle Tag des Napoleon Lippfischs","datePublished":"2023-08-10T12:35:33+00:00","dateModified":"2023-08-11T05:34:19+00:00","mainEntityOfPage":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"image":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg","keywords":["Einsteigertour","Ham Ham","Langnasenb\u00fcschelbarsche","Napoleon"],"articleSection":["T\u00e4gliche Tauchausfahrten"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/","url":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/","name":"Der inoffizielle Tag des Napoleon Lippfischs - James &amp; Mac Diving Center","isPartOf":{"@id":"https:\/\/james-mac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#primaryimage"},"image":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg","datePublished":"2023-08-10T12:35:33+00:00","dateModified":"2023-08-11T05:34:19+00:00","description":"Der inoffizielle Tag des Napoleon Lippfischs und damit Leinen los f\u00fcr unsere t\u00e4glichen Tauchausfahrten im August 2023. Taucht mit uns ab!","breadcrumb":{"@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#primaryimage","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2021\/10\/Napoleon-Lippfisch-Jung-Foto-Sven-4x3-1.jpg","width":1570,"height":1177,"caption":"Der inoffizielle Tag des Napoleon Lippfischs"},{"@type":"BreadcrumbList","@id":"https:\/\/james-mac.com\/der-inoffizielle-tag-des-napoleon-lippfischs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/james-mac.com\/"},{"@type":"ListItem","position":2,"name":"T\u00e4gliche Tauchausfahrten","item":"https:\/\/james-mac.com\/category\/taegliche-tauchausfahrten\/"},{"@type":"ListItem","position":3,"name":"Der inoffizielle Tag des Napoleon Lippfischs"}]},{"@type":"WebSite","@id":"https:\/\/james-mac.com\/#website","url":"https:\/\/james-mac.com\/","name":"James &amp; Mac Diving Center","description":"Red sea diving since 1987","publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/james-mac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/james-mac.com\/#organization","name":"James &amp; Mac","url":"https:\/\/james-mac.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/03\/JM-Logo-Neu-Ohne-Schrift-Klein.png","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2020\/03\/JM-Logo-Neu-Ohne-Schrift-Klein.png","width":400,"height":193,"caption":"James & Mac"},"image":{"@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jamesandmac\/","https:\/\/x.com\/James_Mac_HRG","https:\/\/www.instagram.com\/jamesundmacdiving\/","https:\/\/www.youtube.com\/user\/james1987mac"]},{"@type":"Person","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4","name":"Ameli","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","caption":"Ameli"},"url":"https:\/\/james-mac.com\/en\/author\/ameli\/"}]}},"_links":{"self":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/40131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/comments?post=40131"}],"version-history":[{"count":9,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/40131\/revisions"}],"predecessor-version":[{"id":40141,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/40131\/revisions\/40141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media\/23918"}],"wp:attachment":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media?parent=40131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/categories?post=40131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/tags?post=40131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}