
{"id":53657,"date":"2025-08-09T06:29:00","date_gmt":"2025-08-09T04:29:00","guid":{"rendered":"https:\/\/james-mac.com\/?p=53657"},"modified":"2025-08-09T07:44:27","modified_gmt":"2025-08-09T05:44:27","slug":"sommer-am-roten-meer-unser-wochenrueckblick","status":"publish","type":"post","link":"https:\/\/james-mac.com\/en\/sommer-am-roten-meer-unser-wochenrueckblick\/","title":{"rendered":"Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"53657\" class=\"elementor elementor-53657\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-227703b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"227703b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4ad3dd\" data-id=\"f4ad3dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc199a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc199a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fa3966e\" data-id=\"fa3966e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f56543a elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"2f56543a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/wir-starten-in-den-neuen-monat-august\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Voriger<\/span><span class=\"post-navigation__prev--title\">Wir starten in den neuen Monat August<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/unsere-hochsommerliche-wochenrundschau\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster<\/span><span class=\"post-navigation__next--title\">Unsere hochsommerliche Wochenrundschau<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15897ef elementor-widget elementor-widget-spacer\" data-id=\"15897ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fcd9eb elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9fcd9eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6cddf elementor-align-center elementor-widget elementor-widget-post-info\" data-id=\"5d6cddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-3db2e1d elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/james-mac.com\/en\/2025\/08\/09\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>09.08.2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1242fe7 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"1242fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-1024x768.jpg\" class=\"attachment-large size-large wp-image-46718\" alt=\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-2048x1536.jpg 2048w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-155x116.jpg 155w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-657f44db elementor-widget elementor-widget-spacer\" data-id=\"657f44db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd68d7e elementor-widget elementor-widget-heading\" data-id=\"1dd68d7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sommer am Roten Meer - unser Wochenr\u00fcckblick<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51b9a289 elementor-widget elementor-widget-text-editor\" data-id=\"51b9a289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Willkommen zu unserem aktuellen Wochenbericht vom Roten Meer! Jede Woche nehmen wir euch hier mit in die faszinierende Unterwasserwelt \u00c4gyptens, berichten von <a href=\"https:\/\/james-mac.com\/en\/taegliche-tauchausfahrten\/\" target=\"_blank\" rel=\"noopener\">spannenden Tauchg\u00e4ngen<\/a>, stellen unseren Fisch der Woche vor und werfen einen Blick auf aktuelle Entwicklungen aus dem Land der Pharaonen. Au\u00dferdem gibt es immer wieder n\u00fctzliche Tipps und Empfehlungen f\u00fcr alle, die ihren Urlaub in \u00c4gypten noch entspannter und erlebnisreicher gestalten m\u00f6chten. Viel Spa\u00df beim Lesen und Abtauchen! Sommer am Roten Meer &#8211; unser Wochenr\u00fcckblick auf eine Sommerwoche in \u00c4gypten:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2280868d elementor-widget elementor-widget-spacer\" data-id=\"2280868d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9b5b75 elementor-widget elementor-widget-image\" data-id=\"b9b5b75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1.jpg\" class=\"attachment-full size-full wp-image-53220\" alt=\"Sommer am Roten Meer - unser Wochenr\u00fcckblick\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1.jpg 2560w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-2048x1536.jpg 2048w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/07\/Taucher-Korallengarten-Foto-Thorsten-4x3-1-155x116.jpg 155w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d5e3d0 elementor-widget elementor-widget-spacer\" data-id=\"5d5e3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-113b441 elementor-widget elementor-widget-heading\" data-id=\"113b441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wracks und sommerliches Tauchvergn\u00fcgen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f2fc6d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0f2fc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir starteten fr\u00f6hlich ins letzte Wochenende und alle Altmetallfans waren ganz aufgeregt. Denn das Motto lautete zwei Tage lang: \u201eIt\u2019s Wrack-Time\u201c. Zum Ein\u00fcben und schon mal warm werden starteten wir am Samstag mit einer <a href=\"https:\/\/james-mac.com\/en\/jedes-wrack-hat-seine-eigene-geschichte\/\" target=\"_blank\" rel=\"noopener\">Wracktour<\/a> rund um Hurghada. Als erstes Wrack stand die El Minja im Hafenbecken auf dem Plan. Weiter ging es dann an der Excalibur und zum Tagesabschluss folgte Wrack Nummer 3, unser Haus- und Lieblingswrack: die Balena.\u00a0<\/p><p>Am Sonntag machten wir uns dann auf die Reise zur <a href=\"https:\/\/james-mac.com\/en\/wracktraeume-bei-klarer-sicht\/\" target=\"_blank\" rel=\"noopener\">Thistlegorm<\/a>. Nicht nur Cousteau war von diesem Juwel unter den betauchbaren Wracks begeistert, auch wir sind es heute noch. Nach zwei spannenden Dives ging es mit neuen Eindr\u00fccken im Gep\u00e4ck wieder retour Richtung Heimathafen. Nat\u00fcrlich waren auch diejenigen auf dem Roten Meer unterwegs, die f\u00fcr Wracktauchen nicht so viel \u00fcbrig hatten. Als Alternative gabs Delfine in Shaab Helua und Schildkr\u00f6ten rund um Giftun.\u00a0<\/p><p>Die neue Woche startete windstill und k\u00f6niglich sonnig im Norden. Shaab Rur und das Carless Reef boten wie \u00fcblich eine bunte Korallenwelt und fischtechnisch von allem etwas. Wer vom Altmetall noch nicht genug hatte, der konnte sich in Shaab Quais die alten Milit\u00e4rfahrzeuge anschauen. <span style=\"letter-spacing: 0px;\">\u00dcben, \u00fcben, \u00fcben hie\u00df es am Dienstag. Unsere Open-Water-Sch\u00fcler wurden in die Kunst des Tauchens eingewiesen, unsere Divemaster-Trainees in die Kunst des Assistierens beim Tauchkurs. Alle machten ihre Sache gro\u00dfartig und so stand auch dem Tauchvergn\u00fcgen an sich nichts im Weg. In Fanadir gab es wieder jede Menge Giftiges zu entdecken und bunte Korallen obendrein.<\/span><\/p><p>Ein spontaner Clean-up-Tauchgang brachte am Mittwoch einen <a href=\"https:\/\/james-mac.com\/en\/erstaunliche-funde-beim-spontanen-clean-up\/\" target=\"_blank\" rel=\"noopener\">seltsamen Fund<\/a> zutage &#8211; jemand hatte anscheinend sein Gebiss verloren. Erstaunlicherweise ist das nicht das Erste, das wir Unterwasser gefuden haben &#8230; Mit weitaus sch\u00f6neren Sichtungen in Form von B\u00fcffelkopf-Papageifischen ging dann auch diese sch\u00f6ne Woche zu Ende und wir sind schon gespannt auf die n\u00e4chste!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd6590 elementor-widget elementor-widget-spacer\" data-id=\"fdd6590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87af94f elementor-widget elementor-widget-video\" data-id=\"87af94f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/XnTpgLy5vDA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72d076f elementor-widget elementor-widget-spacer\" data-id=\"72d076f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4bfbb elementor-widget elementor-widget-heading\" data-id=\"7d4bfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Unser Meerestier der Woche: Der Geisterpfeifenfisch<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa57c84 elementor-widget elementor-widget-text-editor\" data-id=\"aa57c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wer im Roten Meer taucht, begegnet einer unglaublichen Vielfalt faszinierender Meeresbewohner. Einer der verborgensten Sch\u00e4tze unter ihnen ist der\u00a0<a class=\"c-link\" href=\"https:\/\/www.starfish.ch\/Korallenriff\/Geisterpfeifenfisch.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.starfish.ch\/Korallenriff\/Geisterpfeifenfisch.html\" data-sk=\"tooltip_parent\">Geisterpfeifenfisch<\/a>. Er ist ein Meister der Tarnung und Eleganz, der selbst erfahrenen Tauchern oft verborgen bleibt.<\/p><p>Geisterpfeifenfische (Solenostomidae) wirken auf den ersten Blick wie schwebende Algen oder zarte Pflanzenfasern. Sie werden bis zu 17 cm lang, ihr K\u00f6rper ist langgezogen, durchsichtig oder in kr\u00e4ftigen Farben gemustert, mit auff\u00e4llig gro\u00dfen, f\u00e4cherartigen Flossen. Besonders eindrucksvoll ist ihre F\u00e4higkeit, sich farblich an ihre Umgebung anzupassen. So verstecken sie sich perfekt zwischen Weichkorallen, Gorgonien, Schwarzen Korallen oder Federsternen. Auf diese Weise werden sie nahezu unsichtbar.<\/p><p>Im Gegensatz zu ihren Verwandten, den Seenadeln oder Seepferdchen oder\u00a0<a class=\"c-link\" href=\"https:\/\/www.tierchenwelt.de\/seenadelartige\/4228-fetzenfisch.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.tierchenwelt.de\/seenadelartige\/4228-fetzenfisch.html\" data-sk=\"tooltip_parent\">Fetzenfischen<\/a>, leben Geisterpfeifenfische nur als Erwachsene frei schwimmend. Die meiste Zeit verbringen sie mit dem Kopf nach unten in der Str\u00f6mung, scheinbar regungslos. Dabei handelt es sich in der Regel um Paare, M\u00e4nnchen und Weibchen, die gemeinsam durch das Riff treiben. Beim Geisterpfeifenfisch \u00fcbernimmt das Weibchen die Brutpflege. Es tr\u00e4gt die befruchteten Eier in einer Art Brutbeutel zwischen den Bauchflossen, bis die Jungfische schl\u00fcpfen. Danach sterben die Tiere \u00fcberwiegend \u2013 ein kurzer, aber faszinierender Lebenszyklus.<\/p><p>Im Roten Meer sind\u00a0<a class=\"c-link\" href=\"https:\/\/www.meerwasser-lexikon.de\/kategorie\/112.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.meerwasser-lexikon.de\/kategorie\/112.html\" data-sk=\"tooltip_parent\">Geisterpfeifenfische<\/a>\u00a0nicht h\u00e4ufig anzutreffen, aber sie kommen regelm\u00e4\u00dfig vor. Vor allem an ruhigen Riffen mit vielen Verstecken sind sie daheim. Rund um Hurghada, Marsa Alam oder auf den Brother Islands kann man sie mit etwas Gl\u00fcck entdecken, besonders in den Monaten mit wenig Str\u00f6mung. Wer sie sehen m\u00f6chte, braucht ein gutes Auge &#8211; oder einen erfahrenen Guide. \ud83d\ude09<\/p><p>Der Geisterpfeifenfisch ist ein Paradebeispiel f\u00fcr die verborgenen Wunder der Unterwasserwelt. Wer ihn entdeckt, wird mit einem seltenen Anblick belohnt und dem Gef\u00fchl, Zeuge eines kleinen Naturwunders geworden zu sein. Also: Augen auf beim n\u00e4chsten Tauchgang im Roten Meer \u2026 Vielleicht schwebt einer schon ganz in eurer N\u00e4he!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13ceb87c elementor-widget elementor-widget-spacer\" data-id=\"13ceb87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f74905 elementor-widget elementor-widget-image\" data-id=\"7f74905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1.jpg\" class=\"attachment-full size-full wp-image-53648\" alt=\"Telephony App\" srcset=\"https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1.jpg 2560w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-300x225.jpg 300w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-1024x768.jpg 1024w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-768x576.jpg 768w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-1536x1152.jpg 1536w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-2048x1536.jpg 2048w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-16x12.jpg 16w, https:\/\/james-mac.com\/wp-content\/uploads\/2025\/08\/Telephony-4x3-1-155x116.jpg 155w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b431e0a elementor-widget elementor-widget-spacer\" data-id=\"b431e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-389c9a69 elementor-widget elementor-widget-heading\" data-id=\"389c9a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einfuhr von Mobilger\u00e4ten wird nun unter Umst\u00e4nden besteuert<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-655c917 elementor-widget elementor-widget-text-editor\" data-id=\"655c917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr einige Verwirrung sorgt nach wie vor ein (nun nicht mehr ganz so) neues Gesetz in \u00c4gypten, das die Einfuhr von neuen Mobiltelefonen regeln soll. Konkret hei\u00dft das: Wer mit einem Mobiltelefon nach \u00c4gypten einreist und vorhat, sich eine \u00e4gyptische Telefon- oder Datenkarte zuzulegen, muss seit Anfang des Jahres unter Umst\u00e4nden\u00a0<a class=\"c-link\" href=\"https:\/\/english.ahram.org.eg\/NewsContent\/3\/1239\/538141\/Business\/Tech\/Explainer-How-Egypt-new-electronic-system-regulati.aspx\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/english.ahram.org.eg\/NewsContent\/3\/1239\/538141\/Business\/Tech\/Explainer-How-Egypt-new-electronic-system-regulati.aspx\" data-sk=\"tooltip_parent\">einiges beachten<\/a>. Wir haben die neuen Regeln, so gut es geht, f\u00fcr euch zusammengefasst:<\/p><p>Erst einmal die gute Nachricht: Wer mit seinem Mobiltelefon und einer \u00e4gyptischen Karte bereits vor dem 1.1.2025 in \u00c4gypten eingeloggt war, f\u00fcr den bleibt alles beim Alten. Es ist keine Registrierung erforderlich und das Handy funktioniert auch weiterhin dauerhaft wie gewohnt. Genauso verh\u00e4lt es sich, wenn man nur seine deutsche Karte im Handy hat und ausschlie\u00dflich \u00fcber WLAN ins Internet geht. In \u00c4gypten auf offiziellem Wege gekaufte Mobiltelefone sind ebenfalls nicht von der Importsteuer betroffen.<\/p><p>Wer allerdings ein neues Handy mitbringt oder im Jahr 2025 zum ersten Mal eine \u00e4gyptische Telefonkarte in sein Handy einlegt, der muss die <a class=\"c-link\" href=\"https:\/\/de.wikipedia.org\/wiki\/International_Mobile_Equipment_Identity\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/de.wikipedia.org\/wiki\/International_Mobile_Equipment_Identity\" data-sk=\"tooltip_parent\">IMEI<\/a> seines Ger\u00e4ts ab sofort bei der Einreise nach \u00c4gypten registrieren lassen, sofern er vorhat, \u00f6fter nach \u00c4gypten zu reisen oder l\u00e4nger als drei Monate zu bleiben. Tut er das nicht, wird das Ger\u00e4t nach drei Monaten f\u00fcr das \u00e4gyptische Telefonnetz gesperrt und es ist eine Zahlung zur dauerhaften Freischaltung n\u00f6tig. Diese drei Monate enden auch nicht, wenn man das Land wieder verl\u00e4sst. Die zu zahlende Geb\u00fchr ist vom Wert des Mobilger\u00e4ts abh\u00e4ngig. Auf <a class=\"c-link\" href=\"https:\/\/www.egypttoday.com\/Article\/1\/137416\/Egypt-launches-app-to-register-mobile-phones-from-abroad-with\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.egypttoday.com\/Article\/1\/137416\/Egypt-launches-app-to-register-mobile-phones-from-abroad-with\" data-sk=\"tooltip_parent\">importierte Ger\u00e4te<\/a>\u00a0wird eine Steuer\/Zoll von circa 38,5\u202f% erhoben, basierend auf dem Ger\u00e4tepreis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c65db9 elementor-widget elementor-widget-heading\" data-id=\"5c65db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Freistellung f\u00fcr den pers\u00f6nlichen Gebrauch ist m\u00f6glich<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d300576 elementor-widget elementor-widget-text-editor\" data-id=\"d300576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jeder Reisende kann (alle drei Jahre) ein Ger\u00e4t f\u00fcr den pers\u00f6nlichen Gebrauch komplett steuerfrei einf\u00fchren und dauerhaft nutzen, muss es jedoch noch im Flughafen direkt nach der Einreise beim Zoll anmelden. Das funktioniert folgenderma\u00dfen: Nachdem man seinen Koffer vom Band geholt hat, begibt man sich zur letzten Kofferkontrolle vor dem Ausgang. Dort wendet man sich an einen Beamten und erkl\u00e4rt ihm, dass man sein Mobiltelefon registrieren lassen m\u00f6chte. Der Beamte kontrolliert und fotografiert den Reisepass, gibt einen Code ins Handy ein und fotografiert das Ergebnis (Strichcode) ab. Das Mobiltelefon ist nun kostenfrei registriert und dauerhaft freigeschaltet. Wir haben das selbst getestet, die Registrierung hat ganz einfach, schnell und problemlos funktioniert.<\/p><p>Man kann sein Telefon auch nachtr\u00e4glich mithilfe der\u00a0<a class=\"c-link\" href=\"https:\/\/english.ahram.org.eg\/News\/537827.aspx\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/english.ahram.org.eg\/News\/537827.aspx\" data-sk=\"tooltip_parent\">Telephony-App<\/a> registrieren lassen. Allerdings ist man dann nicht von der Steuer befreit und muss den geforderten Betrag bezahlen, um sein Ger\u00e4t dauerhaft nutzen zu k\u00f6nnen. Zudem l\u00e4sst sich die Telephony-App nicht auf jedem Ger\u00e4t problemlos installieren und sie funktioniert offensichtlich auch nicht zuverl\u00e4ssig.\u00a0<\/p><p>Wer eine \u00e4gyptische SIM-Karte benutzen, diese jedoch nicht ins Handy einlegen will, der kann sich einen g\u00fcnstigen <a class=\"c-link\" href=\"https:\/\/www.faz.net\/kaufkompass\/test\/der-beste-mobile-wlan-router\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.faz.net\/kaufkompass\/test\/der-beste-mobile-wlan-router\/\" data-sk=\"tooltip_parent\">mobilen WLAN-Router<\/a> zulegen. So hat man sein eigenes WLAN stets dabei und muss sich keine Sorgen um eine Handysperrung machen. Hierbei ist jedoch zu beachten, dass auch Telefongespr\u00e4che innerhalb \u00c4gyptens nur \u00fcber WLAN m\u00f6glich sind. Kostenloses WLAN gibt es f\u00fcr unsere G\u00e4ste nat\u00fcrlich auch auf unserer Tauchbasis. Oder man schaltet sein Telefon, wenn m\u00f6glich, einfach mal aus und genie\u00dft seinen Urlaub. \ud83d\ude42<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdd6361 elementor-widget elementor-widget-spacer\" data-id=\"bdd6361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb2978 elementor-widget elementor-widget-video\" data-id=\"8bb2978\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/cM20zSuo_04?si=EZ5m51GOp2AlPUs1&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-681304c elementor-widget elementor-widget-spacer\" data-id=\"681304c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4556563b elementor-widget elementor-widget-heading\" data-id=\"4556563b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Moses k\u00f6nnte in alt\u00e4gyptischen Mineninschriften genannt sein<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bafc2a9 elementor-widget elementor-widget-text-editor\" data-id=\"bafc2a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine kleine Inschrift in einer alten Mine k\u00f6nnte eine gro\u00dfe Geschichte neu schreiben: Hat\u00a0<a class=\"c-link\" href=\"https:\/\/www.geo.de\/wissen\/weltgeschichte\/moses--held-der-bibel--befreier-der-israeliten-30196538.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.geo.de\/wissen\/weltgeschichte\/moses--held-der-bibel--befreier-der-israeliten-30196538.html\" data-sk=\"tooltip_parent\">Mose<\/a>, die zentrale Figur des biblischen Exodus, tats\u00e4chlich existiert? Der unabh\u00e4ngige Forscher Michael S. Bar-Ron ist davon \u00fcberzeugt, seitdem er zwei rund 3.800 Jahre alte\u00a0<a class=\"c-link\" href=\"https:\/\/archaeologymag.com\/2025\/07\/moses-may-be-named-in-egyptian-mine-inscriptions\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/archaeologymag.com\/2025\/07\/moses-may-be-named-in-egyptian-mine-inscriptions\/\" data-sk=\"tooltip_parent\">Inschriften<\/a> in der \u00e4gyptischen T\u00fcrkismine Serabit el-Khadim im Sinai untersucht hat. Laut seiner These beinhalten die protosinaitischen Zeichen an der Wand Formulierungen wie \u201ezot mi\u2019Moshe\u201c (\u201eDies ist von Mose\u201c) und \u201ene\u2019um Moshe\u201c (\u201eEin Spruch Moses\u201c).<\/p><p>Sollte sich seine <a class=\"c-link\" href=\"https:\/\/www.artnews.com\/art-news\/news\/inscription-claims-spark-debate-around-historical-moses-1234748783\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.artnews.com\/art-news\/news\/inscription-claims-spark-debate-around-historical-moses-1234748783\/\" data-sk=\"tooltip_parent\">Vermutung<\/a> best\u00e4tigen, w\u00e4ren dies die \u00e4ltesten bekannten au\u00dferbiblischen Hinweise auf Mose. Das w\u00e4re eine Sensation, denn bislang fehlt ein arch\u00e4ologischer Beweis f\u00fcr seine Existenz. Die Inschriften stammen vermutlich von semitischen Arbeitern, die zur Zeit des Pharaos Amenemhet III. im Sinai T\u00fcrkis abbauten. Die protosinaitische Schriftform ist eine Vorl\u00e4uferin des sp\u00e4teren Alphabets und schwer zu entschl\u00fcsseln, was die Theorie angreifbar macht. Bar-Ron vermutet, dass ein einzelner Schreiber mit Kenntnissen der Hieroglyphen religi\u00f6se und pers\u00f6nliche Botschaften hinterlie\u00df. Einige Inschriften rufen die Gottheit \u201eEl\u201c an, andere preisen \u201eBa\u02bfalat\u201c, das semitische Gegenst\u00fcck zur \u00e4gyptischen G\u00f6ttin Hathor. Anzeichen f\u00fcr einen religi\u00f6sen Konflikt \u2013 etwa ausgel\u00f6schte Texte, ein niedergebrannter Tempel und der Ausdruck \u201eni\u2019mosh&#8220; (\u201eLasst uns aufbrechen\u201d) \u2013 lassen sogar an den Exodus denken.<\/p><p>Weitere Funde wie das Siegel eines semitischst\u00e4mmigen Beamten und die Stele des Reniseneb weisen auf eine bedeutende semitische Pr\u00e4senz im Gebiet hin. Die Fachwelt <a class=\"c-link\" href=\"https:\/\/www.morgenpost.de\/panorama\/article409629008\/mysterioese-inschrift-in-aegyptischer-hoehle-entdeckt-von-moses.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"https:\/\/www.morgenpost.de\/panorama\/article409629008\/mysterioese-inschrift-in-aegyptischer-hoehle-entdeckt-von-moses.html\" data-sk=\"tooltip_parent\">reagiert gespalten<\/a>: W\u00e4hrend sein Betreuer Dr. Pieter van der Veen die Forschung unterst\u00fctzt, bezeichnet der \u00c4gyptologe Dr. Thomas Schneider die Interpretation als \u201eunbelegt und irref\u00fchrend\u201c. Bar-Ron selbst ist sich wohl auch nicht ganz sicher und hofft auf weitere Forschung.<\/p><p>Ob Mose nun in Stein verewigt wurde oder nicht: Die Funde von Serabit el-Khadim werfen ein faszinierendes Licht auf die religi\u00f6sen und kulturellen Umbr\u00fcche im alten \u00c4gypten und zeigen, wie nah Mythos und Geschichte manchmal beieinanderliegen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-570961d elementor-widget elementor-widget-spacer\" data-id=\"570961d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6a64da elementor-widget elementor-widget-heading\" data-id=\"c6a64da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83e\udd13 Unser Schlaumeier der Woche - Halbwissen f\u00fcr echte Profis \ud83e\udd13<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a5e43b elementor-widget elementor-widget-text-editor\" data-id=\"1a5e43b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Schon gewusst? Im Roten Meer liegt eines der gr\u00f6\u00dften k\u00fcnstliche Riff der Welt, doch das war nie so geplant. Vor der K\u00fcste \u00c4gyptens, bei Shaab Abu Nuhas, liegen gleich mehrere gesunkene Frachtschiffe dicht beieinander. Es sind so viele, dass der Ort unter Tauchern als \u201eSchiffsfriedhof des Roten Meeres\u201c bekannt ist. Hier findet man die ber\u00fchmte Giannis D, Carnatic, Chrisoula K und Kimon M. Manche vermuten, dass es sogar sieben Wracks rund um Abu Nuhas gibt, doch das ist nicht bewiesen.<\/p>\n<p>Der Grund f\u00fcr diese Wrackdichte ist ein f\u00fcr Schiffe gef\u00e4hrliches Riff, das nur knapp unter der Wasseroberfl\u00e4che liegt und \u00fcber Jahrzehnte hinweg Kapit\u00e4ne in die Irre f\u00fchrte. Besonders t\u00fcckisch war die N\u00e4he zu einer stark befahrenen Schifffahrtsroute und schlechte Navigationshilfen bis in die 80er-Jahre. Heute ist die Gegend ein Hotspot f\u00fcr Wracktauchg\u00e4nge und eines ist sicher: Das Abu Nuhas-Riff hat mehr Schiffe \u201egefressen\u201c als manche St\u00fcrme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b54ea0e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b54ea0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b337408 elementor-widget elementor-widget-heading\" data-id=\"b337408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sommer am Roten Meer - Unser Wochenr\u00fcckblick<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69fa36c3 elementor-widget elementor-widget-text-editor\" data-id=\"69fa36c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das war\u2019s f\u00fcr diese Woche vom Roten Meer. Wir hoffen, euch hat unser Wochenbericht gefallen. Bleibt neugierig, passt auf euch auf und bis zum n\u00e4chsten Mal, mit neuen Eindr\u00fccken aus dem Land zwischen W\u00fcste und Wasser!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4151c811 elementor-widget elementor-widget-text-editor\" data-id=\"4151c811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick, James &amp; Mac Diving Center \u2013 Fotonachweise: James &amp; Mac,\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sommer am Roten Meer &#8211; unser Wochenr\u00fcckblick Willkommen zu unserem aktuellen Wochenbericht vom Roten Meer! Jede Woche nehmen wir euch hier mit in die faszinierende Unterwasserwelt \u00c4gyptens, berichten von spannenden Tauchg\u00e4ngen, stellen unseren Fisch der Woche vor und werfen einen Blick auf aktuelle Entwicklungen aus dem Land der Pharaonen. Au\u00dferdem gibt es immer wieder n\u00fctzliche Tipps und Empfehlungen f\u00fcr alle, die ihren Urlaub in \u00c4gypten noch entspannter und erlebnisreicher gestalten m\u00f6chten. Viel Spa\u00df beim Lesen und Abtauchen! Sommer am Roten&hellip;<\/p>","protected":false},"author":4,"featured_media":46718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1322,136,170,135,413,355],"class_list":["post-53657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-rotes-meer","tag-1322","tag-aegypten","tag-hurghada","tag-rotes-meer","tag-rueckblick","tag-wochenrueckblick","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center<\/title>\n<meta name=\"description\" content=\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/james-mac.com\/en\/sommer-am-roten-meer-unser-wochenrueckblick\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center\" \/>\n<meta property=\"og:description\" content=\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/james-mac.com\/en\/sommer-am-roten-meer-unser-wochenrueckblick\/\" \/>\n<meta property=\"og:site_name\" content=\"James &amp; Mac Diving Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jamesandmac\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-09T04:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-09T05:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ameli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:site\" content=\"@James_Mac_HRG\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ameli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/\"},\"author\":{\"name\":\"Ameli\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\"},\"headline\":\"Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick\",\"datePublished\":\"2025-08-09T04:29:00+00:00\",\"dateModified\":\"2025-08-09T05:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/\"},\"wordCount\":1867,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/KAT-20240514-37-scaled.jpg\",\"keywords\":[\"2025\",\"\u00c4gypten\",\"Hurghada\",\"Rotes Meer\",\"R\u00fcckblick\",\"Wochenr\u00fcckblick\"],\"articleSection\":[\"Blog Rotes Meer\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/\",\"url\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/\",\"name\":\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/KAT-20240514-37-scaled.jpg\",\"datePublished\":\"2025-08-09T04:29:00+00:00\",\"dateModified\":\"2025-08-09T05:44:27+00:00\",\"description\":\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#primaryimage\",\"url\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/KAT-20240514-37-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/james-mac.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/KAT-20240514-37-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Sommer am Roten Meer - Unser Wochenr\u00fcckblick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/sommer-am-roten-meer-unser-wochenrueckblick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/james-mac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog Rotes Meer\",\"item\":\"https:\\\/\\\/james-mac.com\\\/en\\\/category\\\/blog-rotes-meer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#website\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"name\":\"James &amp; Mac Diving Center\",\"description\":\"Red sea diving since 1987\",\"publisher\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/james-mac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#organization\",\"name\":\"James & Mac\",\"url\":\"https:\\\/\\\/james-mac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"James & Mac\"},\"image\":{\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jamesandmac\\\/\",\"https:\\\/\\\/x.com\\\/James_Mac_HRG\",\"https:\\\/\\\/www.instagram.com\\\/jamesundmacdiving\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/james1987mac\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/james-mac.com\\\/#\\\/schema\\\/person\\\/bdad9b5a4498bd11efeed74d2676eee4\",\"name\":\"Ameli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g\",\"caption\":\"Ameli\"},\"url\":\"https:\\\/\\\/james-mac.com\\\/en\\\/author\\\/ameli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center","description":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/james-mac.com\/en\/sommer-am-roten-meer-unser-wochenrueckblick\/","og_locale":"en_GB","og_type":"article","og_title":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center","og_description":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.","og_url":"https:\/\/james-mac.com\/en\/sommer-am-roten-meer-unser-wochenrueckblick\/","og_site_name":"James &amp; Mac Diving Center","article_publisher":"https:\/\/www.facebook.com\/jamesandmac\/","article_published_time":"2025-08-09T04:29:00+00:00","article_modified_time":"2025-08-09T05:44:27+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg","type":"image\/jpeg"}],"author":"Ameli","twitter_card":"summary_large_image","twitter_creator":"@James_Mac_HRG","twitter_site":"@James_Mac_HRG","twitter_misc":{"Written by":"Ameli","Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#article","isPartOf":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/"},"author":{"name":"Ameli","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4"},"headline":"Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick","datePublished":"2025-08-09T04:29:00+00:00","dateModified":"2025-08-09T05:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/"},"wordCount":1867,"commentCount":0,"publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"image":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg","keywords":["2025","\u00c4gypten","Hurghada","Rotes Meer","R\u00fcckblick","Wochenr\u00fcckblick"],"articleSection":["Blog Rotes Meer"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/","url":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/","name":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick - James &amp; Mac Diving Center","isPartOf":{"@id":"https:\/\/james-mac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#primaryimage"},"image":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#primaryimage"},"thumbnailUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg","datePublished":"2025-08-09T04:29:00+00:00","dateModified":"2025-08-09T05:44:27+00:00","description":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick. Jede Woche pr\u00e4sentieren wir euch Aktuelles und Spannendes, frisch vom Roten Meer.","breadcrumb":{"@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#primaryimage","url":"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg","contentUrl":"https:\/\/james-mac.com\/wp-content\/uploads\/2024\/05\/KAT-20240514-37-scaled.jpg","width":2560,"height":1920,"caption":"Sommer am Roten Meer - Unser Wochenr\u00fcckblick"},{"@type":"BreadcrumbList","@id":"https:\/\/james-mac.com\/sommer-am-roten-meer-unser-wochenrueckblick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/james-mac.com\/"},{"@type":"ListItem","position":2,"name":"Blog Rotes Meer","item":"https:\/\/james-mac.com\/en\/category\/blog-rotes-meer\/"},{"@type":"ListItem","position":3,"name":"Sommer am Roten Meer &#8211; Unser Wochenr\u00fcckblick"}]},{"@type":"WebSite","@id":"https:\/\/james-mac.com\/#website","url":"https:\/\/james-mac.com\/","name":"James &amp; Mac Diving Center","description":"Red sea diving since 1987","publisher":{"@id":"https:\/\/james-mac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/james-mac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/james-mac.com\/#organization","name":"James &amp; Mac","url":"https:\/\/james-mac.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"James & Mac"},"image":{"@id":"https:\/\/james-mac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jamesandmac\/","https:\/\/x.com\/James_Mac_HRG","https:\/\/www.instagram.com\/jamesundmacdiving\/","https:\/\/www.youtube.com\/user\/james1987mac"]},{"@type":"Person","@id":"https:\/\/james-mac.com\/#\/schema\/person\/bdad9b5a4498bd11efeed74d2676eee4","name":"Ameli","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/815b16a62dd9759f01ae110606d38d9d0fe57f307e2639ca16c1d626d7a6762d?s=96&r=g","caption":"Ameli"},"url":"https:\/\/james-mac.com\/en\/author\/ameli\/"}]}},"_links":{"self":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/53657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/comments?post=53657"}],"version-history":[{"count":35,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/53657\/revisions"}],"predecessor-version":[{"id":53708,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/posts\/53657\/revisions\/53708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media\/46718"}],"wp:attachment":[{"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/media?parent=53657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/categories?post=53657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/james-mac.com\/en\/wp-json\/wp\/v2\/tags?post=53657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}